{"id":928,"date":"2008-07-29T21:10:00","date_gmt":"2008-07-29T21:10:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=928"},"modified":"2008-07-29T21:10:00","modified_gmt":"2008-07-29T21:10:00","slug":"google-rank","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2008\/07\/29\/google-rank\/","title":{"rendered":"Google Rank"},"content":{"rendered":"<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Per chi non lo sapesse il &quot;Google Rank&quot; &#232; il livello assegnato da Google che dovrebbe in qualche misurare la &quot;fama&quot; di un sito: in sostanza, su una base 10, pi&#249; &#232; alto il rank pi&#249; &#232; alto il posizionamento nel motore di ricerca.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Orbene, per curiosit&#224; ho testato il rank di questo blog: 4 su 10, direi non male&#8230;<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Poi, sempre per curiosit&#224;, ho confrontato quello &quot;ufficiale&quot; della mia ditta.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">2 su 10.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Sono sempre pi&#249; convinto di aver sbagliato lavoro <img decoding=\"async\" src=\"http:\/\/mescal.pixelized.ch\/smilies\/wall.gif\" \/><\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per chi non lo sapesse il &quot;Google Rank&quot; &#232; il livello assegnato da Google che dovrebbe in qualche misurare la &quot;fama&quot; di un sito: in sostanza, su una base 10,&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-928","post","type-post","status-publish","format-standard","hentry","category-still-life"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-eY","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5483,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/06\/16\/scoprendo\/","url_meta":{"origin":928,"position":0},"title":"Scoprendo","author":"Aries","date":"16 Giugno 2016","format":false,"excerpt":"Stasera, in coda mentre attendevo di farmi personalizzare uno splendido volume a fumetti, mi sono trovato a chiacchierare con una ragazza dietro di me.Mi ha raccontato di come il mondo dei fumetti fosse per lei quasi del tutto nuovo, che amava da anni l'opera di Pazienza, che ora si stava\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4760,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/09\/21\/162-il-dizionario-dei-cartoni-animati\/","url_meta":{"origin":928,"position":1},"title":"162. Il dizionario dei cartoni animati","author":"Aries","date":"21 Settembre 2015","format":false,"excerpt":"Alcuni anni fa avevo puntato in libreria questo enorme volume che prometteva di essere summa enciclopedica di tutto ci\u00f2 che c'era da sapere sui cartoni animati di tutto il mondo. Non lo comprai subito, ma mi fu regalato un po' di tempo dopo dalla persona con cui stavo con mia\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2015\/09\/41EVsgFajCL._BO1204203200_.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4253,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/02\/18\/quando-il-diavolo-ti-accarezza\/","url_meta":{"origin":928,"position":2},"title":"Quando il diavolo ti accarezza","author":"Aries","date":"18 Febbraio 2015","format":false,"excerpt":"Non sapevo bene cosa aspettarmi accostandomi a questo (per me) primo libro di Luca Tarenzi. Quando l'avevo comprato sapevo soltanto che Francesco Dimitri ne parlava molto bene (e Dimitri \u00e8 uno dei pochi autori da cui sono disposto a ricevere consigli) ed ero piuttosto curioso, anche se l'idea di una\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2015\/02\/310yrdp5mGL.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":562,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/07\/02\/la-guerra-di-due-mondi\/","url_meta":{"origin":928,"position":3},"title":"La guerra di due mondi","author":"Aries","date":"2 Luglio 2007","format":false,"excerpt":"Il C.U.N. (Centro Ufologico Nazionale) \u00e8 forse l'unico ente privato in Italia che da 42 anni si propone di studiare, approfondire e sviscerare il fenomeno U.F.O. nel modo pi\u00f9 serio possibile: ben lontano dalle facilonerie di tanti esaltati, ma anche dalla cieca chiusura di ambienti quali quelli in cui si\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10644,"url":"https:\/\/oldmanaries.it\/index.php\/2022\/05\/22\/9-del-salone-del-libro\/","url_meta":{"origin":928,"position":4},"title":"9. Del Salone del Libro","author":"Aries","date":"22 Maggio 2022","format":false,"excerpt":"Il mio rapporto col Salone del Libro di Torino \u00e8 cambiato molto negli anni. Durante le mie prime edizioni arrivavo il sabato, mi perdevo tra gli stand e compravo un sacco di libri che probabilmente avrei potuto pagare meno altrove, solo perch\u00e9 ero l\u00ec e potevo. Ammetto che giravo pi\u00f9\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/946AC630-DBC1-4522-B858-0DFA5CB52341-edited.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":1755,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/05\/04\/cambiamenti-2\/","url_meta":{"origin":928,"position":5},"title":"Cambiamenti","author":"Aries","date":"4 Maggio 2006","format":false,"excerpt":"Ci sono luoghi e persone che fanno parte di noi e della nostra natura.Si tratta di quei posti dove ci si sente come a casa propria anche se ci si va raramente, quegli amici (non conoscenti) che sono tali anche se li vedi una volta l'anno.Per me Cesenatico e Max\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=928"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/928\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}