{"id":6230,"date":"2017-02-19T00:07:27","date_gmt":"2017-02-18T23:07:27","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=6230"},"modified":"2017-02-25T20:26:31","modified_gmt":"2017-02-25T19:26:31","slug":"ristampa-n-3-sia-chiaro","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2017\/02\/19\/ristampa-n-3-sia-chiaro\/","title":{"rendered":"Ristampa N. 4: Sia Chiaro"},"content":{"rendered":"<p style=\"text-align: justify;\">Tutti, o quasi, abbiamo una o pi\u00f9 storie passate che hanno lasciato un segno: storie caratterizzate da abitudini, momenti, con sapori e odori propri, se vogliamo.<br \/>\nSono storie che durano settimane, mesi, anni e che prima o poi finiscono perch\u00e9, beh, perch\u00e9 non tutte le cose belle riescono a durare.<br \/>\nQuesto racconto, scritto quasi dieci anni fa (aprile 2007) narra di una di quelle storie.<br \/>\nScritto a partire da una serie di canzoni che mi portarono in quel mood, ispirato, in alcuni punti, a momenti vissuti ed emozioni reali, divenne qualcosa di autonomo.<br \/>\nTutti prima o poi abbiamo guardato indietro chiedendoci se avessimo fatto la scelta giusta: una domanda quasi sempre tanto fine a se stessa quanto umana e quanto, sinceramente, inutile.<br \/>\nEppure ogni tanto \u00e8 l\u00ec.<br \/>\nIl protagonista della storia si fa questa domanda e si risponde nell&#8217;unico modo possibile, quello che gli serve per continuare la sua strada.<br \/>\nBuona (ri)lettura.<\/p>\n<p style=\"text-align: justify;\"><strong>SIA CHIARO<\/strong><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Sia chiaro, una volta per tutte: io non ti amo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Anzi, per essere pi\u00f9 preciso, io non ti amo pi\u00f9.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Se mai ti ho amata.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Gi\u00e0, perch\u00e9 mica ne sono poi cos\u00ec sicuro, sai?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E se non ti avessi amata allora sarebbe giusta la prima versione.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Io non ti amo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Ecco, almeno iniziamo a chiarirlo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Io non ti amo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 semplice, non ti pare?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">D\u2019altronde ti ho lasciata io, giusto? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Allora che senso avrebbe amarti ancora?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">No no, io non ti amo, mettitelo in testa.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Anzi, non riesco proprio a capire come facevo a pensare di amarti, sai?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Mi viene proprio da ridere, \u00e8 talmente assurdo\u2026 amare te! <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Stiamo scherzando?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Dovevo aver fumato qualcosa di strano, ne sono convinto.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">L\u2019effetto magari \u00e8 durato un po\u2019 a lungo, ma \u00e8 l\u2019unica spiegazione.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Cos\u2019avrei dovuto amare di te, me lo spieghi?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Non penserai mica che il fatto che mi perdessi in quegli occhi scuri e luminosi insieme potesse bastare, vero? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Ma figuriamoci\u2026<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E poi? Cos\u2019altro? I singoli sguardi sufficienti a capirci? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Beh, che c\u2019\u00e8 di strano? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Sai con quanti amici mi capita? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Oppure, non so, il nostro giocare a raccontarci le canzoni?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Dai, siamo seri, era un gioco da ragazzini e noi non lo eravamo poi cos\u00ec tanto, su\u2026 <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">S\u00ec, lo so che ti dicevo che adoravo giocare insieme e sentirci bambini, ma non ci avrai mica creduto, vero?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">No, ecco, ci sono: magari doveva essere il tuo profumo, vero?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">S\u00ec, quel profumo che mi faceva impazzire e non capire pi\u00f9 nulla: se quella \u00e8 la tua arma segreta, allora sei messa male\u2026 hai idea di quante donne lo portino, eh? Ne hai idea? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E non pensare subito al fatto che non riuscivamo mai a saziarci di noi, che non attacca: era solo fare l\u2019amor\u2026 no, che sto dicendo? Era passione, quella, passione e basta, niente di pi\u00f9. <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E poi che credi? Che davvero mi facessi tenerezza quando ti commuovevi davanti ad un film? O che amassi davvero cucinare con te? Oppure, mi viene da ridere al solo pensiero, che dormissi poche ore a notte solo per passare pi\u00f9 tempo con te? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Ma per favore, dai, non diciamo stupidate: avevo ben altre motivazioni, io, che credi? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 solo che ora non ricordo quali, ma ti assicuro che c\u2019erano\u2026<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Lo vedi? Se andiamo a pensarci bene, non c\u2019\u00e8 nulla che possa giustificare l\u2019amarti o l\u2019averti amata.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Proprio nulla.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Zero.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Niente.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Niente, capito?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E non credere che il fatto che ricordi ogni tuo e nostro particolare significhi qualcosa, lo sai che ho buona memoria\u2026<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 solo grazie a lei che ricordo i tuoi occhi corrucciati al mattino, \u00e8 solo quella che mi fa tornare alla mente il nostro primo bacio, cos\u00ec come quelli che l\u2019hanno seguito: non \u00e8 assolutamente perch\u00e9 adoravo quel piccolo gemito che facevi quando ti perdevi nel baciarmi, cosa credi? <\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 solo la mia buona memoria che non mi permette di scordarmeli.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Peccato che poi si dimentichi di ricordarmi perch\u00e9 \u00e8 finita, ma questo non conta ora, non provare a distrarmi con questi trabocchetti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Una cosa \u00e8 certa.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Io non ti amo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">No.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Non ti amo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Non voglio amarti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Non posso amarti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Non devo amarti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Anzi, io devo odiarti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Devo ricordare ogni litigata, ogni incomprensione, ogni singolo momento di rabbia e devo scordare che ognuno poi era seguito dal nostro saper fare la pace\u2026<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Io devo odiarti, lo capisci?<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 indispensabile che ti odi.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">E\u2019 l\u2019unico modo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Sono costretto, cerca di capirmi, ti prego.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Devo odiarti perch\u00e9 non posso esserti indifferente.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Devo odiarti.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Devo, per un solo, banale, maledettissimo motivo.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Devo odiarti perch\u00e9 devo provare qualcosa per te.<\/span><br \/>\n<span style=\"font-family: 'times new roman', times, serif; font-size: 12pt;\">Perch\u00e9 altrimenti non averti farebbe troppo male, amore mio.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tutti, o quasi, abbiamo una o pi\u00f9 storie passate che hanno lasciato un segno: storie caratterizzate da abitudini, momenti, con sapori e odori propri, se vogliamo. Sono storie che durano&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_s2mail":"yes","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[206],"tags":[],"class_list":["post-6230","post","type-post","status-publish","format-standard","hentry","category-ristampe"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-1Cu","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6131,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/01\/17\/ricordi-di-ghiaccio\/","url_meta":{"origin":6230,"position":0},"title":"Ricordi di ghiaccio","author":"Aries","date":"17 Gennaio 2017","format":false,"excerpt":"Tutti noi che amiamo leggere abbiamo qualche libro o fumetto che, da ragazzini, abbiamo amato pi\u00f9 degli altri \u00a0tanto da rileggerlo decine e decine di volte. Come si pu\u00f2 immaginare, io ne ho diversi, soprattutto se parliamo di fumetti: i libri sono quasi sempre stati una lettura unica, stranamente. Ricordo\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/01\/Topolino_1411-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6255,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/02\/28\/13-anni-di-noccioline\/","url_meta":{"origin":6230,"position":1},"title":"13 anni di noccioline","author":"Aries","date":"28 Febbraio 2017","format":false,"excerpt":"Quando ero bambino, mi capitava di andare al piano di sopra a giocare con un mio coetaneo. Oddio, era pi\u00f9 frequente che venisse lui a casa (s\u00ec, preferivo stare da me e usare i miei giocattoli anche allora), ma ogni tanto capitava salissi io. Una delle cose che ricordo benissimo\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/02\/Charles_M._Schulz_1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/02\/Charles_M._Schulz_1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/02\/Charles_M._Schulz_1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/02\/Charles_M._Schulz_1.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/02\/Charles_M._Schulz_1.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1096,"url":"https:\/\/oldmanaries.it\/index.php\/2009\/03\/11\/la-fine-del-mondo-e-il-paese-delle-meraviglie\/","url_meta":{"origin":6230,"position":2},"title":"La fine del mondo e il paese delle meraviglie","author":"Aries","date":"11 Marzo 2009","format":false,"excerpt":"Tante volte ho usato, parlando di romanzi di Gaiman o di Dick, il termine \"onirico\". Tante volte ho parlato di pi\u00f9 livelli di lettura e di messaggio in superficie che nasconde qualcosa\u00a0 di ben pi\u00f9 profondo. Mai, per\u00f2, mi era capitato un romanzo che portasse tali caratteristiche ad un livello\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6742,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/12\/01\/delle-conseguenze-di-certi-momenti\/","url_meta":{"origin":6230,"position":3},"title":"Delle conseguenze di certi momenti","author":"Aries","date":"1 Dicembre 2017","format":false,"excerpt":"Ormai quasi una settimana fa ero a un funerale. Mia zia, l'ultima sorella ancora in vita di mia madre. Probabilmente l'ultima volta che l'avevo vista era stata nove anni fa, al funerale di mio padre. Perch\u00e9 va cos\u00ec, soprattutto nella mia vita, e il passato e il presente raramente si\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10955,"url":"https:\/\/oldmanaries.it\/index.php\/2022\/08\/03\/82-da-un-grande-potere\/","url_meta":{"origin":6230,"position":4},"title":"82. Da un grande potere","author":"Aries","date":"3 Agosto 2022","format":false,"excerpt":"(c) Marvel - fonte: Avengers 59 Luned\u00ec \u00e8 stato lo Spider-Man Day. Che palle, si potrebbe dire, ci sono sempre pi\u00f9 \u201dnerd-days\u201d e finiscono per essere pi\u00f9 o meno l\u2019occasione solo per dire \u201c\u00e8 il tale day!\u201d e, forse, sarebbe vero, tant\u2019\u00e8 che mai in passato mi sono posto la\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/08\/spidey.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7105,"url":"https:\/\/oldmanaries.it\/index.php\/2018\/11\/13\/per-lultima-volta-excelsior\/","url_meta":{"origin":6230,"position":5},"title":"Per l&#8217;ultima volta, Excelsior!","author":"Aries","date":"13 Novembre 2018","format":false,"excerpt":"Ho detto e scritto mille volte di essere cresciuto a pane, Saranno Famosi e fumetti Marvel. S\u00ec, certo, il primo fumetto in assoluto \u00e8 stato Topolino, come per praticamente chiunque, ma Topolino non fa testo, Topolino \u00e8 la base su cui poi si \u00e8 poggiato tutto il resto. Ricordo benissimo\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2018\/11\/S101620034.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/6230","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=6230"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/6230\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=6230"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=6230"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=6230"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}