{"id":5735,"date":"2016-09-02T14:35:20","date_gmt":"2016-09-02T12:35:20","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=5735"},"modified":"2021-04-23T09:40:39","modified_gmt":"2021-04-23T07:40:39","slug":"je-suis-o-non-je-suis","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2016\/09\/02\/je-suis-o-non-je-suis\/","title":{"rendered":"Je suis o non Je suis?"},"content":{"rendered":"<p style=\"text-align: justify;\">Ok, data l&#8217;ondata di post al riguardo su Facebook uso casa mia per dire la mia e chi ha voglia legga, chi non ha voglia amen.<br \/>\nLa questione, per chi non lo sapesse, \u00e8 una vignetta pubblicata da Charlie Hebdo nell&#8217;ultimo numero.<\/p>\n<p style=\"text-align: justify;\">La vignetta in questione \u00e8 questa:<\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter \" src=\"https:\/\/www.oldmanaries.it\/wp-content\/uploads\/2016\/09\/CharlieHebdo.jpg\" alt=\"\" width=\"298\" height=\"368\" \/><\/p>\n<p style=\"text-align: justify;\">Ora, partiamo da un paio di premesse che vorrei venissero usate nella lettura di quanto viene dopo.<br \/>\n1. trovo la vignetta in s\u00e9 sicuramente brutta e di cattivo gusto<br \/>\n2. mi sembra piuttosto evidente che l&#8217;intenzione della vignetta\u00a0<strong>non<\/strong> sia deridere i morti ma il fatto che, nel sistema all&#8217;italiana, chi ci rimette sono le persone comuni. Ripeto, fatta in modo assolutamente contestabile, anche ripugnante, se volete, ma di certo non per irridere i morti.<\/p>\n<p style=\"text-align: justify;\">Ci siamo fin qui? Bene.<\/p>\n<p style=\"text-align: justify;\">Ora passiamo per\u00f2 a chiarire un paio di cose: molta gente si \u00e8 indignata gridando allo scandalo, al disgusto, anche alla censura e hanno ricevuto in risposta commenti, anche piuttosto supponenti, di chi risponde &#8220;ma come? non eravate tutti Charlie? e ora vi scandalizzate?&#8221;.<\/p>\n<p style=\"text-align: justify;\">Per favore, cerchiamo di contestualizzare le cose, ok?<\/p>\n<p style=\"text-align: justify;\">Quando ci fu la nota vicenda, dire &#8220;Je suis Charlie&#8221; era, fondamentalmente, dire &#8220;nessuno deve morire per avere fatto vignette anche se insultanti o brutte&#8221;. Non era affermare &#8220;no, ragazzi, Charlie ha sempre pubblicato roba perfetta e non criticabile&#8221;.<br \/>\nSi nota la differenza, vero?<br \/>\nIo ho detto &#8220;Je suis Charlie&#8221; e lo dico ancora, ma come esigo che venga rispettato il diritto di satira, esigo anche di avere il diritto di affermare che una certa satira la trovo triste, offensiva, di cattivo gusto o, semplicemente, brutta.<br \/>\nPer la cronaca: molte vignette su Maometto o sul Cristianesimo pubblicate da Charlie sono state assolutamente altrettanto criticabili e, conoscendo il mio rapporto con la religione, si dovrebbe capire quanto mi ritenga super partes al riguardo.<br \/>\nCharlie ha questo (o questa mancanza di) stile: non l&#8217;ho mai comprato, non lo comprer\u00f2 mai, ne sono consapevole e rimango comunque convinto di quel &#8220;Je suis Charlie&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il punto che fa la differenza \u00e8 il livello di reazione a cui si \u00e8 disposti ad arrivare:<\/p>\n<p style=\"text-align: justify;\">Si pu\u00f2 dire che fa schifo? S\u00ec, \u00e8 legittimo e nessuno pu\u00f2 assumersi il diritto di affermare il contrario: soprattutto pu\u00f2 giocare sul &#8220;Je suis Charlie&#8221; per dire &#8220;ora non potete criticare&#8221;; criticare \u00e8 un conto, chiedere la censura un altro, uccidere un altro ancora. La prima cosa \u00e8 legittima, le altre due no.<br \/>\nSi pu\u00f2 dire che magari ci sarebbe voluto un maggior gusto nella scelta di vignetta e tempi? Certo che si pu\u00f2, \u00e8 sicuramente un diritto, ma non si pu\u00f2 pretendere da Charlie, dato che non \u00e8 esattamente nelle corde di questo giornale porsi questioni del genere.<br \/>\nSi pu\u00f2 chiedere la censura o la chiusura? Come detto sopra, no. Fortemente no. Perch\u00e9 se si chiede la censura a causa di buon gusto, nulla vieta che prima o poi la si possa chiedere perch\u00e9, che ne so, pubblica foto di due uomini che si sposano.<br \/>\nSi deve morire perch\u00e9 si pubblicano vignette di merda? Devo rispondere davvero a questa domanda?<\/p>\n<p style=\"text-align: justify;\">Quindi, da una parte criticate pure Charlie, ma ricordandovi che questo \u00e8 il contenuto che ha\u00a0<em>sempre<\/em> pubblicato e che l&#8217;indignazione solo su alcuni temi \u00e8 un po&#8217; sospetta e lascia il fianco al dubbio che ci si indigni solo se toccati sul vivo, ma, dall&#8217;altra, lasciate che chi prova schifo per una certa vignetta lo dica: la satira dev&#8217;essere libera espressione, ma deve anche\u00a0<em>accettare<\/em> la libera espressione di ritorno.<br \/>\nLasciate che lo dica finch\u00e9 non ne chiede la censura o la chiusura o peggio e no, non \u00e8 in contraddizione con dire Je suis Charlie e se non ne vedete la differenza mi spiace sinceramente.<\/p>\n<p style=\"text-align: justify;\">Da parte mia, se non si fosse capito, ribadisco la mia posizione: la vignetta \u00e8 brutta e probabilmente fuori luogo. Detto questo, Charlie ha diritto di pubblicarla e chiunque si ritenga offeso di criticarla e, nel caso, non comprarlo pi\u00f9:\u00a0ma d&#8217;altronde dubito che, in Italia, molti comprino o abbiano mai comprato Charlie Hebdo, sbaglio?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ok, data l&#8217;ondata di post al riguardo su Facebook uso casa mia per dire la mia e chi ha voglia legga, chi non ha voglia amen. La questione, per chi&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"yes","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[],"class_list":["post-5735","post","type-post","status-publish","format-standard","hentry","category-riflessioni"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-1uv","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6145,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/01\/22\/ognuno-ha-gli-eroi-che-si-sceglie\/","url_meta":{"origin":5735,"position":0},"title":"Ognuno ha gli eroi che si sceglie","author":"Aries","date":"22 Gennaio 2017","format":false,"excerpt":"Charlie Hebdo ha, per la seconda volta, fatto una vignetta che ha fatto incazzare gli italiani. Una vignetta brutta, ma difficilmente tra le (poche) vignette di Hebdo che mi sia capitato di vedere ne ho trovata una bella. Tutta piuttosto grevi o provocatorie, alcune erano mirate decentemente, altre totalmente fuori\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1498,"url":"https:\/\/oldmanaries.it\/index.php\/2011\/02\/13\/un-bambino-ed-il-suo-tigrotto\/","url_meta":{"origin":5735,"position":1},"title":"Un bambino ed il suo tigrotto","author":"Aries","date":"13 Febbraio 2011","format":false,"excerpt":"Difficile credere che qualcuno possa non conoscere Calvin & Hobbes, la splendida striscia ideata e disegnata da Bill Watterson dal novembre 1985 al dicembre 1995. Difficile perch\u00e9 anche se magari non si ha avuto l'occasione di leggerla assiduamente o anche sporadicamente, si tratta di una di quelle opere che sono\u2026","rel":"","context":"In &quot;Bill Watterson&quot;","block_context":{"text":"Bill Watterson","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/bill-watterson\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/themeekgroup.com\/Snowmen\/CalvinAndHobbesSnowman.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":547,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/06\/18\/ed-oggi-tocca-a\/","url_meta":{"origin":5735,"position":2},"title":"Ed oggi tocca a&#8230;","author":"Aries","date":"18 Giugno 2007","format":false,"excerpt":"Alla Svitata che compie gli anni e non ha assolutamente insistito per avere la vignetta di auguri :)","rel":"","context":"In &quot;Comics r us&quot;","block_context":{"text":"Comics r us","link":"https:\/\/oldmanaries.it\/index.php\/category\/comics-r-us\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":569,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/07\/08\/ora-si-puo\/","url_meta":{"origin":5735,"position":3},"title":"Ora si pu\u00f2&#8230;","author":"Aries","date":"8 Luglio 2007","format":false,"excerpt":"Ieri \u00e8 stato il compleanno di Marcy, ma visto che la vignetta di Ombre era anche il bigliettino di auguri che accompagnava il suo regalo ho aspettato oggi per pubblicarla: dopo che la destinataria ha pi\u00f9 che gradito posso farla vedere anche a tutti gli altri :)","rel":"","context":"In &quot;Comics r us&quot;","block_context":{"text":"Comics r us","link":"https:\/\/oldmanaries.it\/index.php\/category\/comics-r-us\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":544,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/06\/15\/ma-sono-nate-tutte-in-questo-periodo\/","url_meta":{"origin":5735,"position":4},"title":"Ma sono nate tutte in questo periodo?","author":"Aries","date":"15 Giugno 2007","format":false,"excerpt":"Fatto sta che oggi Caterinapin compie gli anni, indi per cui BUON COMPLEANNO, CATE! Aggiornamento: come promesso ecco la vignetta di auguri, con tanti ringraziamenti alla velocit\u00e0 di Sean","rel":"","context":"In &quot;Varie ed eventuali&quot;","block_context":{"text":"Varie ed eventuali","link":"https:\/\/oldmanaries.it\/index.php\/category\/varie-ed-eventuali\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6131,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/01\/17\/ricordi-di-ghiaccio\/","url_meta":{"origin":5735,"position":5},"title":"Ricordi di ghiaccio","author":"Aries","date":"17 Gennaio 2017","format":false,"excerpt":"Tutti noi che amiamo leggere abbiamo qualche libro o fumetto che, da ragazzini, abbiamo amato pi\u00f9 degli altri \u00a0tanto da rileggerlo decine e decine di volte. Come si pu\u00f2 immaginare, io ne ho diversi, soprattutto se parliamo di fumetti: i libri sono quasi sempre stati una lettura unica, stranamente. Ricordo\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2017\/01\/Topolino_1411-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/5735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=5735"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/5735\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=5735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=5735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=5735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}