{"id":5020,"date":"2016-01-02T23:14:24","date_gmt":"2016-01-02T22:14:24","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=5020"},"modified":"2016-01-03T00:14:26","modified_gmt":"2016-01-02T23:14:26","slug":"265-provvedimenti-molto-utili","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2016\/01\/02\/265-provvedimenti-molto-utili\/","title":{"rendered":"265. Provvedimenti molto utili"},"content":{"rendered":"<p style=\"text-align: justify;\">Date le condizioni di salute di Zen, ultimamente sto tenendo la camera da letto chiusa sia quando sono in casa che quando esco.<\/p>\n<p style=\"text-align: justify;\">Il grigio, infatti, ama molto sia il letto che una panca vicino al termosifone, ma purtroppo il rischio che ci vomiti sopra \u00e8 troppo elevato per poterglieli lasciare sfruttare.<\/p>\n<p style=\"text-align: justify;\">Stasera, quindi, ci siamo vestiti per uscire a cena entrando e uscendo dalla camera chiudendola sempre alle nostre spalle e lasciandola chiusa andando via.<\/p>\n<p style=\"text-align: justify;\">Rientriamo.<\/p>\n<p style=\"text-align: justify;\">Cerco Zen per dargli la medicina.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 nel trasportino.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 nella cuccia.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 in cucina.<\/p>\n<p style=\"text-align: justify;\">Non \u00e8 dietro la cyclette.<\/p>\n<p style=\"text-align: justify;\">Inizio a preoccuparmi, quando Miss Sauron apre la porta della camera e scoppia a ridere.<\/p>\n<p style=\"text-align: justify;\">Nella stanza in cui non doveva essere, in mezzo al letto che doveva evitare si trovava lui, abbioccato in posizione da sfinge, che ci guardava come se fosse la cosa pi\u00f9 normale del mondo e, anzi, avesse apprezzato la privacy della stanza chiusa.<\/p>\n<p style=\"text-align: justify;\">Perch\u00e9 pu\u00f2 essere anche molto malato, ma il mio felino continua a essere dritto come pochi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Date le condizioni di salute di Zen, ultimamente sto tenendo la camera da letto chiusa sia quando sono in casa che quando esco. Il grigio, infatti, ama molto sia il&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,172],"tags":[],"class_list":["post-5020","post","type-post","status-publish","format-standard","hentry","category-still-life","category-un-post-al-giorno"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-1iY","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5196,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/03\/10\/336-della-perdita\/","url_meta":{"origin":5020,"position":0},"title":"333. Della perdita","author":"Aries","date":"10 Marzo 2016","format":false,"excerpt":"Faccio una premessa. Non so quanto ancora parler\u00f2 di Zen qui sopra, questa potrebbe essere l'ultima volta o l'ennesima. Per me scrivere \u00e8 parte del processo di elaborazione. Uno sfogo, un modo di esternare, un modo anche di tener traccia di ci\u00f2 che provo. Legittimo che possa venire a noia,\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"12592346_10208666439599265_6997051991882796813_n","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2016\/03\/12592346_10208666439599265_6997051991882796813_n-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2016\/03\/12592346_10208666439599265_6997051991882796813_n-1.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2016\/03\/12592346_10208666439599265_6997051991882796813_n-1.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2016\/03\/12592346_10208666439599265_6997051991882796813_n-1.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":6810,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/12\/27\/cio-che-eri\/","url_meta":{"origin":5020,"position":1},"title":"Ci\u00f2 che eri.","author":"Aries","date":"27 Dicembre 2017","format":false,"excerpt":"Non riesco a comprendere come sia trascorsa gi\u00e0 una settimana. Eppure, se ci penso, sembra ancora pi\u00f9 lontano. Lontano e vicino, come ogni dannata volta il cui il dolore diventa insopportabile. Ti ho pensato non so quante volte, piccolo mio: ho cercato di distrarmi e grazie anche a tante persone\u2026","rel":"","context":"In &quot;Dolore&quot;","block_context":{"text":"Dolore","link":"https:\/\/oldmanaries.it\/index.php\/category\/dolore\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/12\/IMG_8223.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":7480,"url":"https:\/\/oldmanaries.it\/index.php\/2019\/12\/21\/dopo-2\/","url_meta":{"origin":5020,"position":2},"title":"Dopo","author":"Aries","date":"21 Dicembre 2019","format":false,"excerpt":"E cos\u00ec \u00e8 appena trascorso il giorno che segna gli undici anni. E due, da quando anche Stitch mi ha lasciato. Stasera Sasha ha voluto dormirmi tra le gambe quasi tutta sera. Tu conoscevi Stitch. Tu mi avevi dato Zen. Mi hai lasciato tu, mi hanno lasciato loro. E so,\u2026","rel":"","context":"In &quot;Dolore&quot;","block_context":{"text":"Dolore","link":"https:\/\/oldmanaries.it\/index.php\/category\/dolore\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5133,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/02\/19\/313-casa-via-da-casa\/","url_meta":{"origin":5020,"position":3},"title":"313. Casa via da casa","author":"Aries","date":"19 Febbraio 2016","format":false,"excerpt":"Zen, da ormai diversi giorni, \u00e8 troppo debole per saltare su divano o letto. Per questo motivo \u00e8 diventata una piccola abitudine quella, quando vado a dormire, di andarlo a prendere, metterlo sul letto dall'altro lato rispetto al mio e mettermi sotto le coperte.Regolarmente, dopo 10\/15 minuti, si alza, si\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"https:\/\/scontent.cdninstagram.com\/t51.2885-15\/s640x640\/sh0.08\/e35\/12716647_447498195445901_286237361_n.jpg?ig_cache_key=MTE4ODM5NTQ5NTMzMzg1Nzk3Mw%3D%3D.2","width":350,"height":200},"classes":[]},{"id":6674,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/10\/10\/piccole-fragilita\/","url_meta":{"origin":5020,"position":4},"title":"Piccole fragilit\u00e0","author":"Aries","date":"10 Ottobre 2017","format":false,"excerpt":"Chi ha un animale in casa, soprattutto cani e gatti, riconoscer\u00e0 quello di cui sto parlando. L'avere un pet rende, tipicamente, estremamente protettivi nei suoi confronti: ne riconosciamo la dipendenza da noi, la fragilit\u00e0, il bisogno che hanno delle nostre attenzioni (s\u00ec, anche i gatti). Casi\u00a0eccessivi\u00a0a parte, siamo in grado\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1764,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/05\/11\/bellezza-e-praticita-2\/","url_meta":{"origin":5020,"position":5},"title":"Bellezza e praticit\u00e0\u00a0","author":"Aries","date":"11 Maggio 2006","format":false,"excerpt":"Un uomo abituato a vivere da solo da anni come me tende a prendere tre strade diverse quando si tratta di gestire la propria casa: la prima \u00e8 quella dell'entropia assoluta, la situazione in cui il soggetto in questione non entra nel suo appartamento se non ben armato e con\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/5020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=5020"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/5020\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=5020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=5020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=5020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}