{"id":477,"date":"2007-04-13T23:27:00","date_gmt":"2007-04-13T23:27:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=477"},"modified":"2007-04-13T23:27:00","modified_gmt":"2007-04-13T23:27:00","slug":"promemoria-2","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2007\/04\/13\/promemoria-2\/","title":{"rendered":"Promemoria"},"content":{"rendered":"<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Appunto mentale: quando si esce a cena per festeggiare una ricorrenza in un ristornate carino sarebbe d&#8217;uopo assicurarsi che Sweetie, prima di porre le sue delicate labbra al calice di vino, si riempia lo stomaco di cibo sufficiente a foderarle lo stesso.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Un manzo, ad esempio.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Il rischio, in caso contrario, &egrave; di sentirla sproloquiare pi&ugrave; del solito e ridere in maniera inquietante con gli occhi persi nel suo mondo.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Per&ograve; dice che il Bonarda era buono, tanto per la cronaca. <img decoding=\"async\" alt=\"\" src=\"\/editor\/fck\/editor\/images\/smiley\/rhymbox-1.0\/wink.gif\" \/><\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Fine appunto mentale.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Appunto mentale: quando si esce a cena per festeggiare una ricorrenza in un ristornate carino sarebbe d&#8217;uopo assicurarsi che Sweetie, prima di porre le sue delicate labbra al calice di&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-477","post","type-post","status-publish","format-standard","hentry","category-still-life"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-7H","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":2650,"url":"https:\/\/oldmanaries.it\/index.php\/2011\/09\/20\/nb\/","url_meta":{"origin":477,"position":0},"title":"NB","author":"Aries","date":"20 Settembre 2011","format":false,"excerpt":"Appunto mentale. Quando la mattina si ha intenzione di usare la funzione \"Richiama\" per chiamare Sweetie, sarebbe il caso di ricordarsi chi si \u00e8 davvero chiamato per ultimo la sera prima. Sigh.","rel":"","context":"In &quot;Senza categoria&quot;","block_context":{"text":"Senza categoria","link":"https:\/\/oldmanaries.it\/index.php\/category\/senza-categoria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4921,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/11\/21\/222-porpora\/","url_meta":{"origin":477,"position":1},"title":"222. Porpora","author":"Aries","date":"21 Novembre 2015","format":false,"excerpt":"\"Uomo Porpora\".Diciamocelo, \u00e8 un nome parecchio stupido.Un personaggio con la pelle, appunto, color porpora: degno figlio fumettistico degli anni in cui \u00e8 nato.Eppure l'Uomo Porpora, Killgrave, aveva un potere tra i pi\u00f9 pericolosi mai pensati: era in grado di controllare mentalmente le persone, di far fare loro qualunque cosa lui\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2015\/11\/wpid-Photo-20151121003308604-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5573,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/07\/16\/chiarimento\/","url_meta":{"origin":477,"position":2},"title":"Chiarimento","author":"Aries","date":"16 Luglio 2016","format":false,"excerpt":"Non avrei voluto scrivere questo post, ma lo spunto da cui \u00e8 nato quello di ieri mi ha fatto decidere a farlo comunque, anche se probabilmente non dovrebbe servire se non per pochissime persone. Non importa, ormai ho deciso, facciamolo. \u00a0Penso sia da chiarire una cosa: io non sto morendo\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":929,"url":"https:\/\/oldmanaries.it\/index.php\/2008\/07\/30\/appunto\/","url_meta":{"origin":477,"position":3},"title":"Appunto&#8230;","author":"Aries","date":"30 Luglio 2008","format":false,"excerpt":"Stamattina, prima di dedicarmi ad una giornata di relax totale (che ogni tanto ci vuole) dovevo fare una consegna di un oggetto ad un cliente. Ora, il cliente in questione si trova in una zona di Milano in cui trovare posto, anche a pagamento, \u00e8 un terno al lotto, per\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2291,"url":"https:\/\/oldmanaries.it\/index.php\/2011\/03\/20\/uno-straniero-vagabondo\/","url_meta":{"origin":477,"position":4},"title":"Uno straniero vagabondo","author":"Aries","date":"20 Marzo 2011","format":false,"excerpt":"Pi\u00f9 volte, negli anni, mi \u00e8 capitato di sentirmi una specie di \"randagio\" dal punto di vista emotivo e mentale; ci sono stati vari momenti in cui mi sono trovato a distruggere quasi tutto ci\u00f2 che avevo, ci\u00f2 a cui ero arrivato e ricominciare tutto da capo o quasi. Io,\u2026","rel":"","context":"In &quot;Musica&quot;","block_context":{"text":"Musica","link":"https:\/\/oldmanaries.it\/index.php\/category\/musica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1441,"url":"https:\/\/oldmanaries.it\/index.php\/2010\/09\/27\/il-libro-dei-paradossi\/","url_meta":{"origin":477,"position":5},"title":"Il Libro Dei Paradossi","author":"Aries","date":"27 Settembre 2010","format":false,"excerpt":"Cos\"\u00e8 un paradosso? Come dice l\"autore \u00e8 \"un\"affermazione contraria a quanto ci si aspetta o alla credenza comune\". Personalmente ho sempre trovato il concetto di paradosso assolutamente intrigante, il classico tipo di masturbazione mentale che pu\u00f2 fare trascorrere una serata tra discussioni pi\u00f9 o meno profonde ed il rischio di\u00a0\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=477"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/477\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}