{"id":4451,"date":"2015-05-24T18:59:23","date_gmt":"2015-05-24T16:59:23","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=4451"},"modified":"2015-05-24T18:59:29","modified_gmt":"2015-05-24T16:59:29","slug":"42-riconoscere","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2015\/05\/24\/42-riconoscere\/","title":{"rendered":"42. Riconoscere"},"content":{"rendered":"<p style=\"text-align: justify;\">Trascorrere due ore con chi non vedevi da due anni. Averne un po&#8217; paura e stare invece bene. Sentire un peso sollevarsi.<\/p>\n<p style=\"text-align: justify;\">Partire per Torino, di nuovo. <\/p>\n<p style=\"text-align: justify;\">Scoprire un ristorante vegano fantastico. <\/p>\n<p style=\"text-align: justify;\">Vedersi scattare una splendida foto. <\/p>\n<p style=\"text-align: justify;\">Ridere, scherzare. Mangiare bene. Stare bene.<\/p>\n<p style=\"text-align: justify;\">Leggere i tre moschettieri prima di addormentarsi.<\/p>\n<p style=\"text-align: justify;\">Svegliarsi (con qualche accidente a chi fa casino in strada, ma va beh), far colazione cercando di non ascoltare la musica techno in diffusione.<\/p>\n<p style=\"text-align: justify;\">Comprare focaccia per pranzo.<\/p>\n<p style=\"text-align: justify;\">Andare in un parco.<\/p>\n<p style=\"text-align: justify;\">Passeggiare lungo il fiume.<\/p>\n<p style=\"text-align: justify;\">Passeggiare per un finto borgo medievale.<\/p>\n<p style=\"text-align: justify;\">Incontrare uno scoiattolo.<\/p>\n<p style=\"text-align: justify;\">Bere un succo di frutta al tavolino di un bar.<\/p>\n<p style=\"text-align: justify;\">Scrivere seduto allo stesso tavolino.<\/p>\n<p style=\"text-align: justify;\">Tornare indietro, non prima di aver sorriso guardando un cane che abbaia per farsi lanciare il frisbee.<\/p>\n<p style=\"text-align: justify;\">E ricordarsi, ad ogni singolo istante, quant&#8217;\u00e8 bello ricordarsi di riconoscere la bellezza di tutto questo.<\/p>\n<p style=\"text-align: justify;\">Sorridere.<\/p>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/instagram.com\/p\/3D3tMBjIpA\/\" target=\"_blank\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent.cdninstagram.com\/hphotos-xaf1\/t51.2885-15\/e15\/11357637_102889410048670_1906659390_n.jpg\" id=\"blogsy-1432486701233.4067\" class=\"aligncenter\" alt=\"\" width=\"500\" height=\"500\"\/><\/a><\/div>\n<div class=\"separator\" style=\"clear: both; text-align: center;\"><a href=\"https:\/\/instagram.com\/p\/3CexjtjIqD\/\" target=\"_blank\" style=\"margin-left: 1em; margin-right: 1em;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/scontent.cdninstagram.com\/hphotos-xaf1\/t51.2885-15\/e15\/11313360_617169708419291_1001459329_n.jpg\" id=\"blogsy-1432486701256.048\" class=\"aligncenter\" alt=\"\" width=\"500\" height=\"500\"\/><\/a><\/div>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trascorrere due ore con chi non vedevi da due anni. Averne un po&#8217; paura e stare invece bene. Sentire un peso sollevarsi. Partire per Torino, di nuovo. Scoprire un ristorante&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4,172],"tags":[],"class_list":["post-4451","post","type-post","status-publish","format-standard","hentry","category-still-life","category-un-post-al-giorno"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-19N","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":5604,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/07\/29\/nuove-solitudini\/","url_meta":{"origin":4451,"position":0},"title":"Nuove solitudini","author":"Aries","date":"29 Luglio 2016","format":false,"excerpt":"Sono giorni, forse settimane, che sto mettendo a fuoco una sensazione generale che \u00e8 sempre meno rumore di fondo e sempre pi\u00f9 qualcosa di definito e reale. La sensazione \u00e8 che molto intorno a me, persone e interazioni, si stiano in qualche modo trasformando in qualcosa di pi\u00f9 instabile e\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5634,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/08\/11\/bene\/","url_meta":{"origin":4451,"position":1},"title":"Bene","author":"Aries","date":"11 Agosto 2016","format":false,"excerpt":"Capita quando meno te lo aspetti, quando non ci pensi, quando stai facendo altro. Nel mio caso eravamo in macchina, oggi pomeriggio. Stavamo andando prima a buttare un paio di cose in discarica e poi a fare un po' di spesa. Mi sono fermato a un automatico per fare il\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4695,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/08\/28\/138-la-mia-milano\/","url_meta":{"origin":4451,"position":2},"title":"138. La mia Milano","author":"Aries","date":"28 Agosto 2015","format":false,"excerpt":"\"Ah, ma Milano \u00e8 brutta\".\"Ah, ma Milano \u00e8 grigia\".\"Ah, ma la cosa pi\u00f9 bella di Milano \u00e8 il treno per Roma\".Non so dire quante volte io e chiunque altro viva a Milano abbia sentito dire queste parole. Milano che non ha niente di bello. Milano che \u00e8 solo lavoro. Milano\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4005,"url":"https:\/\/oldmanaries.it\/index.php\/2014\/08\/06\/una-volta-qui-era-tutta-campagna\/","url_meta":{"origin":4451,"position":3},"title":"Una volta qui era tutta campagna","author":"Aries","date":"6 Agosto 2014","format":false,"excerpt":"Per chi non lo sapesse, la zona di Porta Garibaldi\/Isola a Milano \u00e8 diventata da un po' di tempo il simbolo del rinnovo della citt\u00e0. Nuovi, ricchi palazzi, uffici in stile ipermoderno, un quartiere diventato una delizia per gli occhi, in cui passeggiare, guardarsi intorno rapiti, vivere. Il prezzo \u00e8\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4807,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/10\/05\/176-io-savio-mai\/","url_meta":{"origin":4451,"position":4},"title":"176. Io, savio, mai.","author":"Aries","date":"5 Ottobre 2015","format":false,"excerpt":"Oggi ho carburato veramente poco. Avevo da fare, anzi, ho da fare e ne avr\u00f2 per parecchie settimane (per fortuna), ma non posso certo dire di aver lavorato al 100%. Diciamo che mi sono pi\u00f9 avvicinato al 20%.La sveglia \u00e8 suonata alle 8.30, che (mi rendo conto) \u00e8 un insulto\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1351,"url":"https:\/\/oldmanaries.it\/index.php\/2010\/03\/06\/pro-e-contro\/","url_meta":{"origin":4451,"position":5},"title":"Pro e Contro","author":"Aries","date":"6 Marzo 2010","format":false,"excerpt":"Negativo: Una riunione pomeridiana terminata quasi alle 19, con un elemento su quattro talmente stordito e scassapalle da renderla produttiva un quarto di quanto avrebbe potuto essere e stressante dieci volte il necessario. Positivo: Finire un lavoro da un cliente al mattino, rendermi conto che mancano pi\u00f9 di tre ore\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/4451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=4451"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/4451\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=4451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=4451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=4451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}