{"id":3113,"date":"2012-04-25T11:23:47","date_gmt":"2012-04-25T09:23:47","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=3113"},"modified":"2012-04-25T11:23:47","modified_gmt":"2012-04-25T09:23:47","slug":"storia-curiosa-della-scienza","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2012\/04\/25\/storia-curiosa-della-scienza\/","title":{"rendered":"Storia curiosa della scienza"},"content":{"rendered":"<p style=\"text-align: justify;\">Spiace quando ci si trova a recensire un autore che si ama senza poterne stendere lodi tout-court, ma purtroppo capita e, stavolta, \u00e8 il caso di Flavio Oreglio.<\/p>\n<p style=\"text-align: justify;\">Partiamo da un presupposto: Oreglio \u00e8 indubbiamente un uomo di gran cultura e intelligenza che, per un periodo, ha fatto (bene) anche il comico; partendo con questa premessa ci si pu\u00f2 avvicinare agli ultimi suoi libri con una mente aperta ad affrontare non dei testi comici, bens\u00ec dei saggi che al loro interno dosano anche un po&#8217; di ironia.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec \u00e8 stato per i tre libri del ciclo &#8220;Siamo una massa di ignoranti, parliamone&#8221; che, lo scrissi anche qui, ho adorato per l&#8217;arguzia, per gli spunti e, ovviamente, per il divertimento.<\/p>\n<p style=\"text-align: justify;\">Cos\u00ec, quando \u00e8 uscito &#8220;Storia curiosa della scienza&#8221;, l&#8217;ho comprato fiducioso di trovare una sorta di continuit\u00e0 con le intenzioni \u00a0e lo stile dei precedenti: una continuit\u00e0 che c&#8217;era sicuramente nelle intenzioni, ma non purtroppo nei risultati.<\/p>\n<p style=\"text-align: justify;\">Capiamoci: il libro dimostra per l&#8217;ennesima volta la cultura dell&#8217;autore ed anche il suo amore per la filosofia classica, con un totale rifiuto per l&#8217;ingerenza religiosa verso la scienza&#8230; una posizione che \u00e8 assolutamente allineata alla mia, per essere chiari.<\/p>\n<p style=\"text-align: justify;\">Il problema sta nel come questo testo sviluppa gli argomenti: didascalico, nozionistico, con qualche battuta messa l\u00ec tanto per ricordare che l&#8217;autore sa anche far ridere, ma senza troppa convinzione; in sostanza sembra di leggere un bigino e, invece di affascinare a trasportare in un argomento che effettivamente avrebbe potenzialit\u00e0 enormi, finisce per annoiare o far dire &#8220;tutto qui?&#8221;.<\/p>\n<p style=\"text-align: justify;\">Il problema \u00e8 proprio questo: leggere un libro di un autore che apprezzi e finire col dire &#8220;tutto qui?&#8221;.<\/p>\n<p style=\"text-align: justify;\">Peccato, davvero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Spiace quando ci si trova a recensire un autore che si ama senza poterne stendere lodi tout-court, ma purtroppo capita e, stavolta, \u00e8 il caso di Flavio Oreglio. Partiamo da&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"yes","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[8,136],"tags":[],"class_list":["post-3113","post","type-post","status-publish","format-standard","hentry","category-dalla-mia-libreria","category-flavio-oreglio"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-Od","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":147,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/06\/23\/una-serata-diversa-dal-solito\/","url_meta":{"origin":3113,"position":0},"title":"Una serata diversa dal solito&#8230;","author":"Aries","date":"23 Giugno 2006","format":false,"excerpt":"A volte non ci vuole molto per creare una serata speciale.Uscito per commissioni in quel di Seregno ho ben pensato di proporre a Sweetie una fermata a Monza dopo la sua uscita dall'ufficio: \u00e8 bastato ricordarle dei negozi aperti il gioved\u00ec sera perch\u00e9 accettasse di gran lena Passeggiando per il\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450,"url":"https:\/\/oldmanaries.it\/index.php\/2010\/10\/17\/sentita-e-riportata\/","url_meta":{"origin":3113,"position":1},"title":"Sentita e riportata","author":"Aries","date":"17 Ottobre 2010","format":false,"excerpt":"\"Chi non capisce vota o compra\" (Flavio Oreglio, Recital)","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1218,"url":"https:\/\/oldmanaries.it\/index.php\/2009\/08\/11\/i-grandi-libri\/","url_meta":{"origin":3113,"position":2},"title":"I grandi libri","author":"Aries","date":"11 Agosto 2009","format":false,"excerpt":"Era il 1982. O fore l\"81. Va beh, poco importa, diciamo che avevo tra i 6 e gli 8 anni, cos\u00ec non ci sbagliamo. Mia madre lavorava part time, usciva intorno alle\u00a0 due dal lavoro e veniva a casa, dove mi trovava tornato da scuola: non ricordo chi mi venisse\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3839,"url":"https:\/\/oldmanaries.it\/index.php\/2014\/01\/05\/echo\/","url_meta":{"origin":3113,"position":3},"title":"Echo","author":"Aries","date":"5 Gennaio 2014","format":false,"excerpt":"Sono passati quasi tre anni dall'ultima volta che ho parlato qui sopra di Terry Moore. Nel frattempo ho avuto modo di incontrarlo due volte apprezzandone le qualit\u00e0 umane oltre che di fumettista e mi sono procurato a New York il volume unico della sua seconda opera, Echo, mentre \u00e8 tutt'ora\u2026","rel":"","context":"In &quot;Dalla mia libreria&quot;","block_context":{"text":"Dalla mia libreria","link":"https:\/\/oldmanaries.it\/index.php\/category\/dalla-mia-libreria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/www.oldmanaries.it\/wp-content\/uploads\/2014\/01\/51zYtc0VVtL._.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6421,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/05\/07\/la-macchina-del-tempo\/","url_meta":{"origin":3113,"position":4},"title":"La macchina del tempo","author":"Aries","date":"7 Maggio 2017","format":false,"excerpt":"A volte nuove esperienze arrivano quasi per caso e a due passi da casa o dalla tua seconda casa. Noi, ad esempio, non avevamo sentito parlare della \"Macchina del tempo\" allestita al Museo di Storia di Bologna\u00a0finch\u00e9 alcuni conoscenti ne hanno parlato a Miss Sauron, che subito mi ha proposto\u2026","rel":"","context":"In &quot;Dove andiamo stasera&quot;","block_context":{"text":"Dove andiamo stasera","link":"https:\/\/oldmanaries.it\/index.php\/category\/dove-andiamo-stasera\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5115,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/02\/11\/305-non-illudetemi\/","url_meta":{"origin":3113,"position":5},"title":"305. Non illudetemi","author":"Aries","date":"11 Febbraio 2016","format":false,"excerpt":"Non illudetemi.Non ci provate neanche.Sarebbe crudele e vigliacco da parte vostra.Gi\u00e0 ci hanno pensato la mia infanzia e adolescenza nerd a farlo.Tutte quelle storie in cui l'umanit\u00e0 evolveva, la civilizzazione cresceva, dove il futuro era tra le stelle.Io ci ho creduto.Ho creduto che la civilit\u00e0 potesse andare in quella direzione.Ho\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/3113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=3113"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/3113\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=3113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=3113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=3113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}