{"id":251,"date":"2006-09-19T21:50:00","date_gmt":"2006-09-19T21:50:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=251"},"modified":"2006-09-19T21:50:00","modified_gmt":"2006-09-19T21:50:00","slug":"progetti","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2006\/09\/19\/progetti\/","title":{"rendered":"Progetti"},"content":{"rendered":"<p align=\"justify\"><font size=\"2\">Cerco di organizzare i progetti in corso utilizzando un software di gestione che mi fornisce, a grandi linee, la suddivisione del lavoro giorno per giorno.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Ho impostato 8 ore di lavoro completo al giorno e gli ho chiesto di finire tutto entro il 30 settembre.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Risultato: secondo lui mercoled&igrave; e gioved&igrave; dovrei lavorare almeno 12 ore al giorno.<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Anche a voi qualcosa non quadra?<\/font><\/p>\n<p align=\"justify\"><font size=\"2\">Io emigro, ho deciso&#8230;<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerco di organizzare i progetti in corso utilizzando un software di gestione che mi fornisce, a grandi linee, la suddivisione del lavoro giorno per giorno. Ho impostato 8 ore di&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-251","post","type-post","status-publish","format-standard","hentry","category-still-life"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s8QUWp-progetti","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3089,"url":"https:\/\/oldmanaries.it\/index.php\/2012\/04\/05\/richieste-il-seguito\/","url_meta":{"origin":251,"position":0},"title":"Richieste &#8211; Il seguito","author":"Aries","date":"5 Aprile 2012","format":false,"excerpt":"(per la puntata precedente si vada qui:\u00a0http:\/\/www.oldmanaries.it\/index.php\/2012\/03\/30\/richieste\/) Ebbene s\u00ec, sono tornati all'attacco. O meglio, dopo il figlio ha chiamato il padre (ma come? Non doveva essere il figlio a spiegarsi e capire meglio?). - Buongiorno, senta, ho parlato con mio figlio, ma mi sa che l'altro giorno non ha capito\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4945,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/11\/30\/232-torniamo-sullargomento\/","url_meta":{"origin":251,"position":1},"title":"232. Torniamo sull&#8217;argomento","author":"Aries","date":"30 Novembre 2015","format":false,"excerpt":"Una delle tante cose che vengono sottovalutate quando si parla del lavoro autonomo \u00e8 la gestione delle tempistiche.Sarebbe bello poter lavorare per progetti consequenziali, in cui finito uno ne inizia un altro e, insieme, garantiscono una continuit\u00e0 di entrate che solo chi \u00e8 in proprio sa quanto sia una chimera.Ovviamente\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":3654,"url":"https:\/\/oldmanaries.it\/index.php\/2013\/04\/30\/decisioni-2\/","url_meta":{"origin":251,"position":2},"title":"Decisioni","author":"Aries","date":"30 Aprile 2013","format":false,"excerpt":"Oggi ho avuto l'ennesima dimostrazione che la scelta relativa al mio lavoro \u00e8 corretta. Tra due mesi esatti lascer\u00f2 il cliente che mi ha accompagnato, parzialmente o meno, negli ultimi sette anni. Perch\u00e9, onestamente, per quanto un fatturato regolare sia importante non posso e non voglio pi\u00f9 lavorare in un\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4747,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/09\/15\/156-costanti\/","url_meta":{"origin":251,"position":3},"title":"156. Costanti","author":"Aries","date":"15 Settembre 2015","format":false,"excerpt":"Giornata intensa.Sette ore in piedi a presentare un software a persone che ne sapevano poco o nulla, per spiegare loro non solo come si usa ma, soprattutto, perch\u00e9 avrebbe migliorato il loro lavoro.Dopo, per gradire, tre ore di macchina per tornare a casa.Eppure oggi ho avuto la conferma che certe\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2350,"url":"https:\/\/oldmanaries.it\/index.php\/2011\/04\/14\/furbizia-2\/","url_meta":{"origin":251,"position":4},"title":"Furbizia","author":"Aries","date":"14 Aprile 2011","format":false,"excerpt":"Un cliente ha ricevuto qualche giorno fa il saldo delle ore di lavoro che sono state necessarie per modificare un progetto consegnato a febbraio: tale saldo l'ho diviso in parti pressoch\u00e9 uguali, assorbendo io una parte dei lavori (correzioni di bug e cretinatine varie) ed addebitandogli invece i lavori da\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1162,"url":"https:\/\/oldmanaries.it\/index.php\/2009\/05\/28\/visto-che\/","url_meta":{"origin":251,"position":5},"title":"Visto che&hellip;","author":"Aries","date":"28 Maggio 2009","format":false,"excerpt":"Visto che gli stress in questo periodo non mancano... Visto che settimana prossima ce ne saranno anche di nuovi... Visto che stasera ho gi\u00e0\u00a0 raggiunto le 70 vasche... Visto che fa caldo... Visto che le 10 ore di lavoro al giorno unite a qualche week-end tanto per gradire hanno lasciato\u2026","rel":"","context":"In &quot;Varie ed eventuali&quot;","block_context":{"text":"Varie ed eventuali","link":"https:\/\/oldmanaries.it\/index.php\/category\/varie-ed-eventuali\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=251"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/251\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}