{"id":2442,"date":"2011-05-20T18:33:46","date_gmt":"2011-05-20T16:33:46","guid":{"rendered":"http:\/\/www.ariesblog.it\/?p=2442"},"modified":"2011-05-20T18:33:46","modified_gmt":"2011-05-20T16:33:46","slug":"ok-2","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2011\/05\/20\/ok-2\/","title":{"rendered":"Ok&#8230;"},"content":{"rendered":"<p>Va bene, lo ammetto&#8230; all&#8217;ennesima persona che mi ripete &#8220;ma quanto sei dimagrito<em> (21,3 kg ad oggi &#8211; NdA)<\/em>, ma quanto stai bene, ma complimenti!&#8221; sto iniziando un filo a gongolare&#8230;<\/p>\n<p>&#8230; ma giusto un filo, eh?&#8230;<\/p>\n<p>.<\/p>\n<p>.<\/p>\n<p>.<\/p>\n<p>Ok, va bene, me la sto proprio godendo, ecco, problemi? \ud83d\ude1b<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Va bene, lo ammetto&#8230; all&#8217;ennesima persona che mi ripete &#8220;ma quanto sei dimagrito (21,3 kg ad oggi &#8211; NdA), ma quanto stai bene, ma complimenti!&#8221; sto iniziando un filo a&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[],"class_list":["post-2442","post","type-post","status-publish","format-standard","hentry","category-varie-ed-eventuali"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-Do","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":262,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/09\/28\/una-nuova-chicca\/","url_meta":{"origin":2442,"position":0},"title":"Una nuova chicca","author":"Aries","date":"28 Settembre 2006","format":false,"excerpt":"Basta poco per sfiorare il genio. Nuova telefonata di un cliente impedito. - Senta, come faccio a vedere quanto spazio mi rimane sulla \"chei\" (si riferisce alla chiavetta usb - N.d.A.) - Apra Risorse del computer -> Tasto destro sull'icona -> Propriet\u00e0 e legga - Ah Ok. Cavoli! Mi rimangono\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10745,"url":"https:\/\/oldmanaries.it\/index.php\/2022\/06\/13\/31-il-proprio-valore\/","url_meta":{"origin":2442,"position":1},"title":"31. Il proprio valore","author":"Aries","date":"13 Giugno 2022","format":false,"excerpt":"Photo by Tom Fisk on Pexels.com Per quanto riesca a guardarmi indietro, penso di essere sempre stato molto dicotomico riguardo al mio valore personale. Una parte di me \u00e8 consapevole di chi sono, di quanto valgo, di cosa ho fatto e conquistato, di cosa ho dovuto affrontare e superare: se\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"brown wooden raft on body of water","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/06\/pexels-photo-1706059.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":10607,"url":"https:\/\/oldmanaries.it\/index.php\/2022\/05\/14\/1-da-dove-si-inizia\/","url_meta":{"origin":2442,"position":2},"title":"1. Da dove si inizia?","author":"Aries","date":"14 Maggio 2022","format":false,"excerpt":"Photo by Dom J on Pexels.com La sindrome del foglio bianco \u00e8 conosciuta a chiunque abbia provato a scrivere in modo pi\u00f9 o meno regolare qualcosa di diverso da una lista della spesa (stavo scrivendo \"biglietto d'auguri\", ma in realt\u00e0 a volte arriva pure l\u00ec, non negatelo, lo so io\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"white notebook and yellow pencil","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/05\/pexels-photo-45718.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":699,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/11\/24\/you-must-remember-this\/","url_meta":{"origin":2442,"position":3},"title":"You must remember this","author":"Aries","date":"24 Novembre 2007","format":false,"excerpt":"Stasera ho colmato una grave mancanza guardando per la prima volta Casablanca. E' inutile che mi sprechi in commenti vari, dato che penso sia uno di quei film di cui si \u00e8 detto tutto ed il contrario di tutto, per\u00f2 vorrei aggiungere due mie, forse banali, osservazioni. 1. Ma quanto\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11748,"url":"https:\/\/oldmanaries.it\/index.php\/2026\/03\/02\/ingarbugliato\/","url_meta":{"origin":2442,"position":4},"title":"Ingarbugliato","author":"Aries","date":"2 Marzo 2026","format":false,"excerpt":"Una matassa ingarbugliata. Questa \u00e8 l\u2019immagine che mi \u00e8 venuta fuori poco fa parlando con un\u2019amica. \u00c8 quello che pi\u00f9 rappresenta la mia mente e il mio stato d\u2019animo in questo periodo. \u00c8 tutto cos\u00ec tanto, tutto troppo, che ogni singolo filo di pensiero si attorciglia sugli altri, si annoda,\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2026\/03\/lana.webp?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2026\/03\/lana.webp?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2026\/03\/lana.webp?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2026\/03\/lana.webp?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":4974,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/12\/13\/245-13-dicembre\/","url_meta":{"origin":2442,"position":5},"title":"245. 13 dicembre","author":"Aries","date":"13 Dicembre 2015","format":false,"excerpt":"E dopo aver comprato i regali, qualche giorno dopo, a casa, era il momento di impacchettarli.Tutte attivit\u00e0 a cui mio padre non prendeva parte, eravamo sempre e solo io e mia madre.Io prendevo le scatole, e le porgevo di volta in volta, lei le avvolgeva nelle carte, poi il filo,\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"https:\/\/scontent.cdninstagram.com\/hphotos-xap1\/t51.2885-15\/s640x640\/sh0.08\/e35\/12331581_894101420705046_1060874839_n.jpg","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/2442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=2442"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/2442\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=2442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=2442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=2442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}