{"id":1248,"date":"2009-09-29T20:59:00","date_gmt":"2009-09-29T20:59:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=1248"},"modified":"2009-09-29T20:59:00","modified_gmt":"2009-09-29T20:59:00","slug":"mentore","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2009\/09\/29\/mentore\/","title":{"rendered":"Mentore"},"content":{"rendered":"<p align=\"justify\"><font face=\"Courier New\" size=\"2\">Settimana scorsa \u00e8 nato un nuovo racconto, ispirato ad un personaggio che sento terribilmente mio.     <br \/>Si tratta di qualcosa di totalmente diverso dal precedente, sia per lunghezza che per argomenti e toni.      <br \/>Spero possa comunque piacere.<\/font><\/p>\n<p align=\"justify\"><i><font face=\"Tahoma\" size=\"2\">Guardalo.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Cos\u00ec giovane, mi ricorda un cadetto appena arruolato.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">E&#8217; da un po&#8217; che lo osservo.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Timido, non bello e non brutto, intelligente, ironico.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">E innamorato.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non come si usa tra i suoi coetanei e tra molti che vivono in questo nuovo mondo, dove la parola amore \u00e8 usata alla stregua di qualunque altra, no.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Lui ama.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ama come amavo io.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ama come amava Cristiano.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ama come amava Rossana.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Lui ama.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">E come me teme di esprimerlo alla sua amata.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Come me si strugge nel timore di esser deriso.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">E&#8217; per questo che sono qui.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Per aiutarlo.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Come feci con Cristiano a scapito mio.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Come feci con Cristiano per amor di Rossana, perch\u00e9 lei potesse avere l&#8217;amore assoluto, l&#8217;unico che le spettasse di diritto, il solo che potesse immaginare, fatto di spirito e bell&#8217;aspetto.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Questo cadetto non pecca troppo di fisico, non quanto me.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ora \u00e8 mio compito guidarne lo spirito.       <br \/><\/font><\/i><font size=\"2\"><font face=\"Tahoma\"><i>Gi\u00e0\u00a0 l&#8217;ho indotto a scriverle.         <br \/><\/i><i>Ora facciamo s\u00ec che non siano sproloqui.<\/i><\/font><\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">&#8220;Ti chiederai perch\u00e9 ti sto scrivendo. Ti sembrer\u00e0\u00a0 strano, dato che nessuno scrive pi\u00f9 lettere ormai&#8221;     <br \/><\/font><font size=\"2\"><font face=\"Tahoma\"><i>Bene, forse c&#8217;\u00e8 speranza&#8230; continua&#8230;         <br \/><\/i>&#8220;Ti scrivo perch\u00e9 quando ti guardo lo stomaco si rivolta&#8221;        <br \/><\/font><\/font><font size=\"2\"><font face=\"Tahoma\"><i>Lo stomaco si rivolta? E cos&#8217;\u00e8? Un trattato degno d&#8217;Esculapio? Un po&#8217; di attenzione, giovane cadetto!         <br \/><\/i>&#8220;Ti scrivo perch\u00e9 quando ti sono vicino perdo il coraggio e ci\u00f2 che \u00e8 tanto chiaro nella mia mente non riesce a giungere alle mie labbra&#8221;        <br \/><\/font><\/font><font size=\"2\"><font face=\"Tahoma\"><i>Il cadetto apprende in fretta, vedo         <br \/><\/i>&#8220;Ti scrivo perch\u00e9 ho bisogno di dirti ci\u00f2 che sento, ma temo il cuore non mi regga. Ti scrivo perch\u00e9 ho troppo da dirti ed avr\u00f2 un&#8217;occasione sola&#8221;        <br \/><i>Bravo, cadetto, continua cos\u00ec.<\/i><\/font><\/font><\/p>\n<p align=\"justify\"><i><font face=\"Tahoma\" size=\"2\">Scrivile.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Mostrale il tuo cuore.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Donaglielo come non fosse tuo, perch\u00e9 in realt\u00e0\u00a0 gi\u00e0\u00a0 pi\u00f9 non ti appartiene.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ma, attento, non farlo per il motivo errato.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non mostrarle il tuo cuore per colpirla.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non donarglielo perch\u00e9 ti ami, anche se \u00e8 quanto di pi\u00f9 naturale tu possa fare.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Certo, se ella t&#8217;amer\u00e0\u00a0 sar\u00e0\u00a0 beatitudine e trionfo, sar\u00e0\u00a0 sentire un nuovo sapore nell&#8217;aria, il sapore del suo amore ricambiato, se ella lo vorr\u00e0\u00a0, sarai un dio in una terra di mortali, sarai in grado di sconfiggere cento e pi\u00f9 avversari.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Ma no, giovane cadetto, non sia questo il tuo obiettivo.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Mostrale il tuo cuore per te stesso, perch\u00e9 altrimenti esploderebbe.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Rivelale il tuo amore perch\u00e9 se non lo facessi le nasconderesti te stesso.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Tu non l&#8217;ami perch\u00e9 ella t&#8217;ami.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Tu non l&#8217;ami perch\u00e9 si doni a te.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non l&#8217;ami perch\u00e9 ti guardi.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Tu l&#8217;ami per ci\u00f2 che \u00e8 lei.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Tu l&#8217;ami per ci\u00f2 che vedi e senti.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Tu l&#8217;ami per ci\u00f2 che di lei altri non vedono.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non mostrarle il tuo cuore per vantartene: non c&#8217;\u00e8 vanto nell&#8217;essere se stessi, c&#8217;\u00e8 solo infamia nel non esserlo, nel fingersi ci\u00f2 che non si \u00e8, nel mostrarsi nobili quando si \u00e8 ignobili, coraggiosi quando si \u00e8 codardi, creativi quando si \u00e8 illetterati.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">No, giovane cadetto, la giusta via \u00e8 quella che stai seguendo, per quanto ostica essa sia.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Non la seguirai per ricompense, non per onori, non per lodi, giuramenti sperati o promessi, ma solo per amor tuo, per onor tuo, per il tuo pennacchio.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Potrai invidiare le fortune altrui, potrai odiare la tua strada perch\u00e9 sconnessa e lunga e piena di buche, ma quando giungerai al fine avrai qualcosa che pochi altri avranno.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Te stesso.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Fiero, orgoglioso, un vero guascone.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Certo molti arriveranno e se ne andranno.       <br \/><\/font><\/i><font size=\"2\"><font face=\"Tahoma\"><i>Senza dubbio pochi ti rimarranno accanto, ma saranno i pi\u00f9 leali e sinceri e tu avrai avuto comunque il maggior premio e di questo, solo di questo, dovrai esser lieto.         <br \/><\/i><i>Ma ho divagato mentre scrivevi, vediamo a che punto sei giunto.<\/i><\/font><\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">&#8220;Ecco perch\u00e9 ti ho scritto. Io sono qui. Sono qui per te. Sono qui grazie a te e volevo solo mi vedessi. Magari quel che vedrai ti piacer\u00e0\u00a0, magari no, ma almeno saprai chi sono. Ora posso salutarti, chiamandoti come non osavo all&#8217;inizio di questa lettera.     <br \/>Ciao. Arrivederci. Addio, Amore Mio.&#8221;      <br \/><\/font><i><font face=\"Tahoma\" size=\"2\">Eccellente, giovane cadetto.       <br \/><\/font><\/i><i><font face=\"Tahoma\" size=\"2\">Eccellente.       <br \/><\/font><\/i><font size=\"2\"><font face=\"Tahoma\"><i>Ora puoi fargliela avere, ora puoi condurre il tuo cuore alto come un trofeo.         <br \/><\/i>Il ragazzo si alza, stanco, un po&#8217; confuso.        <br \/>Piega la lettera scritta di suo pugno, la guarda un po&#8217; emozionato, poi la infila in una busta.        <br \/>Ha deciso che andr\u00e0\u00a0 a porla direttamente nella cassetta della posta della sua amata, in silenzio, senza farsi vedere.        <br \/>Sta uscendo, poi si volta verso la scrivania, la stessa scrivania su cui ha scritto poco prima.        <br \/>C&#8217;\u00e8 qualcosa che non c&#8217;era.        <br \/>Si riavvicina, perplesso e curioso.        <br \/>Solleva lo strano oggetto.        <br \/>Leggero, morbido, quasi etereo.        <br \/>Lo osserva e lo trova affascinante, quasi fiero.        <br \/>O sarebbe meglio dire fiera.        <br \/>E&#8217; una penna.        <br \/>Una penna enorme, bianca, imponente&#8230; \u00e8 quasi come appartenesse a&#8230;<\/font><\/font><\/p>\n<p align=\"justify\"><i><font face=\"Tahoma\" size=\"2\">S\u00ec. Ad un pennacchio.<\/font><\/i><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Settimana scorsa \u00e8 nato un nuovo racconto, ispirato ad un personaggio che sento terribilmente mio. Si tratta di qualcosa di totalmente diverso dal precedente, sia per lunghezza che per argomenti&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[5],"tags":[],"class_list":["post-1248","post","type-post","status-publish","format-standard","hentry","category-racconti"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s8QUWp-mentore","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":4121,"url":"https:\/\/oldmanaries.it\/index.php\/2014\/12\/24\/24-dicembre-2014\/","url_meta":{"origin":1248,"position":0},"title":"24 dicembre 2014","author":"Aries","date":"24 Dicembre 2014","format":false,"excerpt":"Mezzanotte e cinquantatre, \u00e8 ufficialmente la Vigilia di Natale. Ho trascorso l'ultima ora a litigare con un upgrade del portatile e ora posso ufficialmente definirmi in ferie, un concetto che mi risulta tanto strano, dopo gli ultimi mesi, che dovr\u00f2 impiegare qualche istante ad abituarmici. Tra poche ore partir\u00f2 per\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":605,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/08\/23\/l-sta-per-chi-ama\/","url_meta":{"origin":1248,"position":1},"title":"L sta per chi ama","author":"Aries","date":"23 Agosto 2007","format":false,"excerpt":"Stasera ho voglia di buoni sentimenti e di un po' di ottimismo: \u00e8 per questo che pubblico in RadioBlog un'allegra canzone di Al Jarreau dal testo magari non impegnatissimo ma comunque molto pieno di speranza. State soffrendo per amore? State soffrendo perch\u00e9 vi manca un vecchio amore o vorreste un\u2026","rel":"","context":"In &quot;Musica&quot;","block_context":{"text":"Musica","link":"https:\/\/oldmanaries.it\/index.php\/category\/musica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":2291,"url":"https:\/\/oldmanaries.it\/index.php\/2011\/03\/20\/uno-straniero-vagabondo\/","url_meta":{"origin":1248,"position":2},"title":"Uno straniero vagabondo","author":"Aries","date":"20 Marzo 2011","format":false,"excerpt":"Pi\u00f9 volte, negli anni, mi \u00e8 capitato di sentirmi una specie di \"randagio\" dal punto di vista emotivo e mentale; ci sono stati vari momenti in cui mi sono trovato a distruggere quasi tutto ci\u00f2 che avevo, ci\u00f2 a cui ero arrivato e ricominciare tutto da capo o quasi. Io,\u2026","rel":"","context":"In &quot;Musica&quot;","block_context":{"text":"Musica","link":"https:\/\/oldmanaries.it\/index.php\/category\/musica\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1753,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/05\/03\/compagni-di-vita-2\/","url_meta":{"origin":1248,"position":3},"title":"Compagni di vita","author":"Aries","date":"3 Maggio 2006","format":false,"excerpt":"Chi non ha mai avuto animali probabilmente non sa di cosa parlo, ma chiunque abbia avuto la fortuna di convivere con un cane, un gatto, un criceto o un nerd mi capir\u00e0 alla perfezione: vivere con un animale vuol dire non soltanto avere un batuffolo peloso (o meno, dato che\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4075,"url":"https:\/\/oldmanaries.it\/index.php\/2014\/10\/03\/again\/","url_meta":{"origin":1248,"position":4},"title":"Again","author":"Aries","date":"3 Ottobre 2014","format":false,"excerpt":"Abbassi la guardia. Pensi che il peggio sia passato, ti piace crederlo, ti piace pensarlo, ti piace illuderti. Ti piace credere che ci sia una base di certezza su cui costruire tutto il resto. Poi arriva il fulmine. Di nuovo. Pi\u00f9 grande e spaventoso del precedente, dei precedenti, perch\u00e9 se\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6286,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/03\/10\/ristampa-n-7-mentore\/","url_meta":{"origin":1248,"position":5},"title":"Ristampa N. 7: Mentore","author":"Aries","date":"10 Marzo 2017","format":false,"excerpt":"S\u00ec, lo so, le ristampe dovrebbero uscire il sabato (sempre che qualcuno le stia leggendo...), ma in questi giorni l'umore non \u00e8 al massimo e, dopo i due post di mercoled\u00ec, sto ricaricandomi lievemente. Niente interruzioni, sia chiaro, ma probabilmente domani non poster\u00f2 e riprender\u00f2 domenica, per cui uso questo\u2026","rel":"","context":"In &quot;Ristampe&quot;","block_context":{"text":"Ristampe","link":"https:\/\/oldmanaries.it\/index.php\/category\/racconti\/ristampe\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2017\/03\/cyrano-de-bergerac.jpeg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=1248"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1248\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=1248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=1248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=1248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}