{"id":1090,"date":"2009-03-05T23:16:00","date_gmt":"2009-03-05T23:16:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=1090"},"modified":"2009-03-05T23:16:00","modified_gmt":"2009-03-05T23:16:00","slug":"non-mi-chiaro","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2009\/03\/05\/non-mi-chiaro\/","title":{"rendered":"Non mi &egrave; chiaro"},"content":{"rendered":"<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Per quale cavolo di motivo su Sky Cinema stanno iniziando a fare certi film catastrofici di serie zeta che neanche Canale 5 d&#8217;estate ha il coraggio di trasmettere?<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Ma, soprattutto, perch&#233; cavolo &#232; la terza sera di fila che trovo il decoder sintonizzato su tali obbrobri?<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Qualcuno pagher&#224;&#8230;<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per quale cavolo di motivo su Sky Cinema stanno iniziando a fare certi film catastrofici di serie zeta che neanche Canale 5 d&#8217;estate ha il coraggio di trasmettere? Ma, soprattutto,&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6,4],"tags":[],"class_list":["post-1090","post","type-post","status-publish","format-standard","hentry","category-riflessioni","category-still-life"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-hA","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3284,"url":"https:\/\/oldmanaries.it\/index.php\/2012\/08\/26\/opening\/","url_meta":{"origin":1090,"position":0},"title":"Opening","author":"Aries","date":"26 Agosto 2012","format":false,"excerpt":"Ma guarda quanta polvere, ma si pu\u00f2? E s\u00ec che mi ero raccomandato... E quello? Che cavolo ci fa l\u00ec? Ma possibile che non ci si possa fidare? Uno si assenta qualche settimana, chiede di non far troppo caos e guarda qui. Va beh, rimbocchiamoci le maniche e... Emb\u00e9? E\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1326,"url":"https:\/\/oldmanaries.it\/index.php\/2010\/01\/27\/non-dico-tanto\/","url_meta":{"origin":1090,"position":1},"title":"Non dico tanto&hellip;","author":"Aries","date":"27 Gennaio 2010","format":false,"excerpt":"Ora, visto che con la macchina sta andando da schifo (per usare un eufemismo), uno si potrebbe anche accontentare di qualcosa di piccolo, giusto? Bene. Qualcosa tipo, non so, il nuovo grattatoio extralusso dei gatti, giusto? Ecco. Giusto. Magari si sapesse dove cavolo \u00e8 finito e l\"azienda rispondesse alle mail\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":494,"url":"https:\/\/oldmanaries.it\/index.php\/2007\/04\/30\/cultoon\/","url_meta":{"origin":1090,"position":2},"title":"Cultoon","author":"Aries","date":"30 Aprile 2007","format":false,"excerpt":"Ebbene s\u00ec, i signori di Sky hanno deciso di commuovermi: da domani comincia le trasmissioni un nuovo canale satellitare (703, segnatevelo) che avr\u00e0 come target gli ex-bambini che tanto amavano gli innumerevoli cartoni nipponici e non che le nostre tv pubbliche e private ci proponevano ad ogni ora. Per capirci,\u2026","rel":"","context":"In &quot;Varie ed eventuali&quot;","block_context":{"text":"Varie ed eventuali","link":"https:\/\/oldmanaries.it\/index.php\/category\/varie-ed-eventuali\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1165,"url":"https:\/\/oldmanaries.it\/index.php\/2009\/06\/02\/chi-lha-visto\/","url_meta":{"origin":1090,"position":3},"title":"Chi l&rsquo;ha visto?","author":"Aries","date":"2 Giugno 2009","format":false,"excerpt":"AAA Cercasi pianta di rosmarino misteriosamente volatilizzatasi. E' stata vista l\"ultima volta in un vaso attaccato ad un balcone interno al quinto piano di uno stabile di Viale Monza. Il vaso ed il terreno sono ancora sul luogo, quindi dovrebbe essere facile riconoscerla: \u00e8 l\"unica con le radici nude. Chiunque\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":314,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/11\/14\/eccoci-arrivati\/","url_meta":{"origin":1090,"position":4},"title":"Eccoci arrivati&#8230;","author":"Aries","date":"14 Novembre 2006","format":false,"excerpt":"Eccomi arrivato ai giorni che gi\u00e0 da settimane temevo e che cominceranno domani. 3 giornate di corso Access Esperto ad utenti di Banca Intesa 1 giornata di corso Visual Basic .Net DI SABATO!!! 2 giornate di corso Excel Macro (e che cavolo gli dico in due giorni quando basterebbero 30\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":149,"url":"https:\/\/oldmanaries.it\/index.php\/2006\/06\/24\/ultimissime-dal-nostro-inviato-al-fronte\/","url_meta":{"origin":1090,"position":5},"title":"Ultimissime dal nostro inviato al fronte","author":"Aries","date":"24 Giugno 2006","format":false,"excerpt":"Si inizia\u2026 Cerco di rendere l\u2019inizio indolore tirando prima fuori la macchina per scrivere e sperando che il gentil genitore si accontenti quel tanto che basta per scordarsi il computer\u2026 Accendiamo la macchina, tiriamo fuori un foglio e la testiamo Sweetie ed io per evitare commenti del cavolo dal gentiluomo\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1090","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=1090"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1090\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=1090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=1090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=1090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}