{"id":1075,"date":"2009-02-14T22:42:00","date_gmt":"2009-02-14T22:42:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=1075"},"modified":"2009-02-14T22:42:00","modified_gmt":"2009-02-14T22:42:00","slug":"flash-2","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2009\/02\/14\/flash-2\/","title":{"rendered":"Flash"},"content":{"rendered":"<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Piccoli Flash di una gita fiorentina di un giorno:<\/font><\/p>\n<ul>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">a Firenze si pu&#242; mangiare meravigliosamente spendendo una cifra ridicola seduti a fianco di perfetti sconosciuti<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">c&#8217;&#232; qualcuno che ha una passione quasi morbosa per il campanile di Giotto<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">se una gelateria in zona centrale &#232; piccola, ha pochi gusti e costa poco &#232; sicuramente ottima: oggi ne ho avuto la conferma davanti a Palazzo Pitti<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">Firenze &#232; una delle poche citt&#224; i cui pu&#242; capitare che una straniera ti chieda se sei italiano<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">c&#8217;&#232; gente capace di guardarsi un filmato sul cellulare rompendo le palle a tutti gli altri passeggeri<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">la Freccia Rossa non &#232; affatto male&#8230; certo, quando non ritarda.<\/font><\/div>\n<\/li>\n<li>\n<div align=\"justify\"><font face=\"Tahoma\" size=\"2\">sono stato in grado di comprare 5 libri anche oggi. E&#8217; ufficiale, sono patologico.<\/font><\/div>\n<\/li>\n<\/ul>\n<p><font face=\"Tahoma\" size=\"2\">Ma soprattutto (e questa la caprianno soprattutto alcuni): VIVA LA LOMBATA ED ABBASSO IL LAMPREDOTTO.<\/font><\/p>\n<p><font face=\"Tahoma\" size=\"2\">Ho detto.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piccoli Flash di una gita fiorentina di un giorno: a Firenze si pu&#242; mangiare meravigliosamente spendendo una cifra ridicola seduti a fianco di perfetti sconosciuti c&#8217;&#232; qualcuno che ha una&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-1075","post","type-post","status-publish","format-standard","hentry","category-still-life"],"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-hl","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":8465,"url":"https:\/\/oldmanaries.it\/index.php\/2018\/01\/18\/the-flash-4x10-the-trial-of-the-flash\/","url_meta":{"origin":1075,"position":0},"title":"The Flash: 4&#215;10 The Trial Of The Flash","author":"Aries","date":"18 Gennaio 2018","format":false,"excerpt":"Le\u00a0vacanze invernali non sembrano aver particolarmente giovato a\u00a0The Flash, che continua il suo percorso partendo da spunti oggettivamente interessanti e promettenti ma gestendoli troppo spesso con una superficialit\u00e0 ingiustificabile. Il titolo \u00e8 volutamente fuorviante, dato che l'episodio \u00e8 necessariamente pi\u00f9 incentrato su\u00a0Barry che sul suo alter-ego e, soprattutto, dato che\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/10e.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/10e.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/10e.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/10e.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/10e.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8498,"url":"https:\/\/oldmanaries.it\/index.php\/2018\/03\/08\/the-flash-4x14-subject-9-4x15-enter-flashtime\/","url_meta":{"origin":1075,"position":1},"title":"The Flash: 4&#215;14 Subject 9 &#8211; 4&#215;15 Enter Flashtime","author":"Aries","date":"8 Marzo 2018","format":false,"excerpt":"Siamo ormai a due terzi della corsa (s\u00ec, l'orribile battuta \u00e8 voluta) di questa stagione di The Flash e l'impressione che siano pi\u00f9 gli ostacoli abbattuti che quelli saltati \u00e8 sempre maggiore. La trama di DeVoe si sta aggrovigliando su se stessa e finisce per ripetere, ogni certo numero di\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/14b.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/14b.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/14b.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/14b.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/14b.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":8406,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/12\/15\/the-flash-4x09-dont-run\/","url_meta":{"origin":1075,"position":2},"title":"The Flash: 4&#215;09 Don&#8217;t Run","author":"Aries","date":"15 Dicembre 2017","format":false,"excerpt":"Quando ci si avvicina al finale di mezza stagione di una serie, \u00e8 ormai consuetudine non tanto chiedersi se ci sar\u00e0 un cliffhanger, ma quale sar\u00e0 e, soprattutto, se sar\u00e0 qualcosa di adeguatamente gestito alla ripresa primaverile.\u00a0The Flash non fa eccezione e ci propone un episodio che di certo vede\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8330,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/11\/24\/the-flash-4x06-when-harry-met-harry-4x07-therefore-i-am\/","url_meta":{"origin":1075,"position":3},"title":"The Flash: 4&#215;06 When Harry Met Harry &#8211; 4&#215;07 Therefore I Am","author":"Aries","date":"24 Novembre 2017","format":false,"excerpt":"Alla vigilia del cross-over stagionale,\u00a0The Flash procede con due episodi dai toni molto diversi tra loro e con risultati altalenanti, pieni di ombre e con qualche piccolo spiraglio di luce. When Harry Met Harry Abbiamo gi\u00e0 accennato a come, in questa stagione, ci sia un tentativo di ritorno ai toni\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6044,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/12\/26\/avanzi-e-ricicciamenti\/","url_meta":{"origin":1075,"position":4},"title":"Avanzi e ricicciamenti","author":"Aries","date":"26 Dicembre 2016","format":false,"excerpt":"Qualche spunto da fine della prima tre giorni festiva, prima di una settimana lavorativa (anche se pi\u00f9 breve delle solite), di qualche giorno di ferie, un matrimonio e varie ed eventuali. Non \u00e8 un post di approfondimento, anzi, \u00e8 pi\u00f9 uno di quelli composti da flash e pensieri sparsi; d'altro\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8196,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/10\/25\/the-flash-4x02-mixed-signals-4x03-luck-be-a-lady\/","url_meta":{"origin":1075,"position":5},"title":"The Flash: 4&#215;02 Mixed Signals &#8211; 4&#215;03 Luck Be A Lady","author":"Aries","date":"25 Ottobre 2017","format":false,"excerpt":"Dopo una season premi\u00e8re\u00a0che aveva lasciato non pochi dubbi sulla qualit\u00e0 della nuova stagione, spiace dire che i due nuovi episodi non solo confermano tali dubbi, ma spostano l'asticella verso il basso, con una serie di scelte che lasciano spiazzati e perplessi. 4x02 Mixed Signals Barry \u00e8 tornato dopo mesi\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/the-flash-4x02-4x03-evidenza.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=1075"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1075\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=1075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=1075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}