{"id":10311,"date":"2021-05-31T17:39:57","date_gmt":"2021-05-31T15:39:57","guid":{"rendered":"https:\/\/www.ariesblog.it\/?p=10311"},"modified":"2021-05-31T17:40:00","modified_gmt":"2021-05-31T15:40:00","slug":"float-on","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2021\/05\/31\/float-on\/","title":{"rendered":"Float on"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973.jpeg\"><img loading=\"lazy\" decoding=\"async\" width=\"1040\" height=\"1300\" src=\"https:\/\/www.oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973.jpeg\" alt=\"fishing motorboats floating in pollute sea water\" class=\"wp-image-10313\" srcset=\"https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973.jpeg 1040w, https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973-240x300.jpeg 240w, https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973-819x1024.jpeg 819w, https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973-768x960.jpeg 768w, https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973-120x150.jpeg 120w\" sizes=\"auto, (max-width: 1040px) 100vw, 1040px\" \/><\/a><figcaption>Photo by Pok Rie on <a href=\"https:\/\/www.pexels.com\/photo\/fishing-motorboats-floating-in-pollute-sea-water-6059973\/\" rel=\"nofollow\">Pexels.com<\/a><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">31 maggio 2021 e quella sensazione di essere una zattera in mezzo al mare non accenna ad affievolirsi. E d&#8217;altronde come potrebbe? Non \u00e8 che qualcosa si sia assestato, non ci sono punti fermi, non ci sono nuovi status quo da usare come fondamenta. C&#8217;\u00e8 un&#8217;unica immensa massa di acqua, terra e fango che si sta spostando da ormai non so pi\u00f9 quanto e che proprio per la sua natura eterogenea finisce per non scorrere neanche allo stesso modo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C&#8217;\u00e8 qualcosa che arriva, sembra volersi fermare e fugge via pi\u00f9 veloce di quanto \u00e8 arrivato, c&#8217;\u00e8 altro che sembrava non potersi staccare e invece \u00e8 bastato un soffio perch\u00e9 venisse portato via, e ancora quello che si stacca, che <strong>doveva<\/strong> staccarsi, ma resta un po&#8217; vicino e un po&#8217; no (senza contare che se sta troppo vicino \u00e8 pi\u00f9 facile che ci porti sotto); ci sono quelle cose che si avvicinano e sembrano volersi agganciare e procedere insieme, ma dati i primi due come si pu\u00f2 dire per quanto reggeranno? <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un gran casino, insomma, che finisce per essere cos\u00ec vario e variegato da non capire come gestirlo tutto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E la mia natura non aiuta, inutile che lo neghi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ci sto lavorando, eh? Ci sto lavorando parecchio e continuo a ringraziare di aver deciso di parlare con una (brava) psicologa. Che poi non \u00e8 che molte delle cose che vengono fuori non le sapessi: non tutte, ma molte s\u00ec. Solo che quando vengono fuori parlando con una persona esterna e in grado di guardare oggettivamente ti rendi conto che quella natura che avevi intuito non \u00e8 solo un intuito. E che hai ingoiato pi\u00f9 rospi di quanti avresti dovuto e voluto e che alcune parole che ti sembravano quasi esagerate finiscono per essere invece perfette. E fa la differenza. Accidenti se fa la differenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E quindi da una parte c&#8217;\u00e8 quello che dev&#8217;essere lasciato indietro, ma che per natura un po&#8217; influenza ancora: \u00e8 difficile accettare quando una persona per cui provavi un legame molto forte ti sbatte un portone in faccia senza motivazioni adeguate; da una parte ti viene da prendere atto e dire &#8220;sai cosa? cazzi tuoi&#8221;, dall&#8217;altra il tuo bisogno di capire scalpita nonostante tu sia il primo a ripetere che purtroppo non sempre puoi capire, per quanto ti girino le palle al pensiero. E c&#8217;\u00e8 sempre quel maledetto bisogno di epifania che fin troppi danni riesce a fare.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ma anche la definizione del presente e, soprattutto, del futuro sono opache a dir poco. \u00c8 stancante il pensiero di trovare nuove affinit\u00e0, di doversi costantemente mostrare per essere visti, anche perch\u00e9 poi nel frattempo quando sembra che qualcosa stia per muoversi si finisce per scoprire che no, spiacente, non \u00e8 cos\u00ec, non ti illudere.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eppure il buono c&#8217;\u00e8 e sarei ingrato e ingiusto a non vederlo. Week-end programmati, una domenica appena trascorsa cos\u00ec improvvisata e ben riuscita da sembrare figlia di tempi molto diversi, ben due cinema in due settimane, un&#8217;amica da vedere gioved\u00ec, la seconda dose del vaccino in arrivo tra meno di tre settimane e, chiss\u00e0, forse una flebile speranza di rivedere Londra prima della fine dell&#8217;estate. Flebile, ripeto, flebilissima, ma non inesistente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00ec, del bello si sta smuovendo. Quale sar\u00e0 il suo ruolo \u00e8 difficile dirlo ora, in quel mare di acqua e fango e detriti in movimento. Forse si former\u00e0 un isolotto. Forse si approder\u00e0 in qualche luogo nuovo. Forse si costruir\u00e0 durante l&#8217;inondazione. O forse arriver\u00e0 una nuova ondata ad affossare tutto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non lo so.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per ora guardo in una direzione senza capire dove si sta andando e mi guardo indietro conscio di quanto sto ancora risolvendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c8 stancante. Molto. Ma ho davvero altra scelta che sia accettabile?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>31 maggio 2021 e quella sensazione di essere una zattera in mezzo al mare non accenna ad affievolirsi. E d&#8217;altronde come potrebbe? Non \u00e8 che qualcosa si sia assestato, non&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":10313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[6],"tags":[570,445,569,567,568],"class_list":["post-10311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-riflessioni","tag-attesa","tag-delusioni","tag-futuro","tag-galleggiare","tag-passato"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/oldmanaries.it\/wp-content\/uploads\/2021\/05\/pexels-photo-6059973.jpeg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-2Gj","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":3492,"url":"https:\/\/oldmanaries.it\/index.php\/2013\/01\/03\/dell-esserci\/","url_meta":{"origin":10311,"position":0},"title":"Dell&#8217;esserci","author":"Aries","date":"3 Gennaio 2013","format":false,"excerpt":"Esserci. E' una delle parole pi\u00f9 importanti, per me. Esserci. Essere presenti. Far sentire che qualcuno pu\u00f2 contare su di noi. Essere una spalla su cui permettere di appoggiarsi. Essere una voce amica. Essere, perch\u00e9 no, un buon cazzeggio. Esserci. E' fondamentale. Ma esserci non significa essere scontati. Essere disponibili\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":11601,"url":"https:\/\/oldmanaries.it\/index.php\/2024\/09\/18\/28-anni-dopo\/","url_meta":{"origin":10311,"position":1},"title":"28 anni dopo","author":"Aries","date":"18 Settembre 2024","format":false,"excerpt":"Cosa potrei scrivere oggi che non ho gi\u00e0 scritto in questa occasione in 28 anni? Che mi manchi? Che ho vissuto pi\u00f9 della mia vita senza te che con te? Che per ricordare la tua voce devo cercare vecchi filmati e che il tuo profumo che avevo tenuto da parte\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2024\/09\/Clipboard01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6279,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/03\/08\/perche-serve-ancora-secondo-me\/","url_meta":{"origin":10311,"position":2},"title":"Perch\u00e9 serve ancora, secondo me.","author":"Aries","date":"8 Marzo 2017","format":false,"excerpt":"Non pensavo di scrivere questo post, oggi, ma vorr\u00e0 dire che ne scriver\u00f2 due. Per come la vedo io, ci sono due tipi di feste: la prima, la pi\u00f9 comune, \u00e8 la festa di celebrazione, dove si celebra, appunto, un anniversario, una ricorrenza, qualcosa di esistente, fosse anche solo una\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":7577,"url":"https:\/\/oldmanaries.it\/index.php\/2020\/03\/19\/piccole-cose-2\/","url_meta":{"origin":10311,"position":3},"title":"Piccole Cose?","author":"Aries","date":"19 Marzo 2020","format":false,"excerpt":"Oggi \u00e8 il 19 marzo. Chi mi conosce sa quanto simbolica per me sia questa data. Prima ancora che mia madre morisse per anni avevamo sempre comprato le zeppole per festeggiare la festa del pap\u00e0. Sempre al forno (lo so, per qualcuno sono inaccettabili, per noi no), sempre alla stessa\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2020\/03\/AnyConv.com__Enjoy_the_little_things_in_life_for_someday_youll_realize_they_were_big_things-scaled.jpg?resize=1400%2C800&ssl=1 4x"},"classes":[]},{"id":5901,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/11\/01\/giudizi-severi\/","url_meta":{"origin":10311,"position":4},"title":"Giudizi severi","author":"Aries","date":"1 Novembre 2016","format":false,"excerpt":"Qualche giorno fa scrivevo altrove che ci sono pochi, pochissimi momenti in cui mi fermo e mi verrebbe voglia di darmi una pacca sulla spalla da solo. Sono quegli istanti in cui mi rendo conto che, nel mio piccolo, con le sole mie forze, sono riuscito a ottenere risultati enormi.\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":10832,"url":"https:\/\/oldmanaries.it\/index.php\/2022\/07\/04\/52-la-maglietta\/","url_meta":{"origin":10311,"position":5},"title":"52. La maglietta","author":"Aries","date":"4 Luglio 2022","format":false,"excerpt":"Photo by MART PRODUCTION on Pexels.com Per motivi che non sto a spiegare qui ora, perch\u00e9 troppo personali, oggi mi sono trovato a riflettere sul senso di responsabilit\u00e0 che abbiamo o dovremmo avere nei confronti degli altri - siano essi amori, amici, parenti, conoscenti. C\u2019\u00e8 chi si carica di pi\u00f9,\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"person in gray shirt holding brown cardboard","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=1050%2C600&ssl=1 3x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2022\/07\/pexels-photo-8078358.jpeg?resize=1400%2C800&ssl=1 4x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/10311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=10311"}],"version-history":[{"count":2,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/10311\/revisions"}],"predecessor-version":[{"id":10314,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/10311\/revisions\/10314"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media\/10313"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=10311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=10311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=10311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}