{"id":1002,"date":"2008-11-05T23:47:00","date_gmt":"2008-11-05T23:47:00","guid":{"rendered":"http:\/\/server:81\/wordpress\/?p=1002"},"modified":"2008-11-05T23:47:00","modified_gmt":"2008-11-05T23:47:00","slug":"aggiornamento-sui-piccioncini","status":"publish","type":"post","link":"https:\/\/oldmanaries.it\/index.php\/2008\/11\/05\/aggiornamento-sui-piccioncini\/","title":{"rendered":"Aggiornamento sui piccioncini"},"content":{"rendered":"<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Evidentemente le mie minacce non fermano il potere degli ormoni e ieri sera erano di nuovo l\u00ec imperterriti.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Ma stavolta ho avuto modo di constatare ancor meglio la situazione, con mio &#8220;sommo gaudio&#8221;.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Orbene, la candida (?) pulzella \u00e8 giunta parecchio prima del portatore sano di ormoni e, sorpresa delle sorprese, ha anche nuotato!<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">(Nota a margine: non \u00e8 che il sottoscritto stia l\u00ec a vedere chi nuota e chi no, ma siamo arrivati insieme ed abbiamo iniziato il giro di vasche nello stesso momento)<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Poi arriva lui.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Bello come il sole durante un&#8217;eclissi totale.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Giunge in vasca.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Ammira la belt\u00e0\u00a0 di lei.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Fa una vasca andata e ritorno tanto per non farle credere di essere andato apposta per l&#8217;intorto e poi SI FERMA.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Ebbene s\u00ec, costui, ormai totalmente scevro da qualunque forma di autostima e pudore, ha passato il resto della serata nell&#8217;angolino ad ammirare (sbavando un po&#8217;, diciamocelo) il di lei nuoto in attesa che lo degnasse delle sue parole e del suo sguardo, cosa che la degna rappresentante del gentil sesso ha ben pensato di fare, ma solo (com&#8217;era d&#8217;uopo) quando ha fatto comodo a lei.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">E chiss\u00e0\u00a0 come sarebbe andata a finire questa meravigliosa favola d&#8217;altri tempi se non fosse giunta la tradizionale secchiata gelata, stavolta nella forma di un brusco calo della temperatura nel lato della piscina in cui i due avevano posto radici: un caso? Un tentativo di un mandrillo geloso di ostacolare il tentativo del giovane virgulto? Un sabotaggio da parte del personale della piscina?<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">La risposta arriver\u00e0\u00a0 magari nella prossima puntata, per ora accontentiamoci ad osservare o immaginare la scena di questo povero intortatore fallito che si allontana mesto con tutte le dita intirizzite e nessun rimorchio definitivo all&#8217;attivo.<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Farebbe quasi tenerezza, vero?<\/font><\/p>\n<p align=\"justify\"><font face=\"Tahoma\" size=\"2\">Certo, non fosse cos\u00ec triste, intendo&#8230;.<\/font><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evidentemente le mie minacce non fermano il potere degli ormoni e ieri sera erano di nuovo l\u00ec imperterriti. Ma stavolta ho avuto modo di constatare ancor meglio la situazione, con&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_s2mail":"","ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-1002","post","type-post","status-publish","format-standard","hentry","category-still-life"],"aioseo_notices":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p8QUWp-ga","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":6191,"url":"https:\/\/oldmanaries.it\/index.php\/2017\/02\/05\/del-catcalling\/","url_meta":{"origin":1002,"position":0},"title":"Del catcalling","author":"Aries","date":"5 Febbraio 2017","format":false,"excerpt":"Ieri sulla bacheca di un'amica ho avuto uno scambio piuttosto spiacevole. Lei si era lamentata che, vestita con la divisa della Croce Rossa, qualcuno l'avesse apostrofata dicendole \"Se perdo i sensi mi rianimi?!\", un classico esempio di catcall. La cosa sarebbe rimasta l\u00ec se un genio non avesse pensato di\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":8691,"url":"https:\/\/oldmanaries.it\/index.php\/2018\/11\/28\/the-gifted-2x08-the-dream\/","url_meta":{"origin":1002,"position":1},"title":"The Gifted: 2&#215;08 the dreaM","author":"Aries","date":"28 Novembre 2018","format":false,"excerpt":"Pi\u00f9 si prosegue in questa seconda stagione di\u00a0The Gifted\u00a0e maggiormente risaltano punti di forza e debolezze di una serie che, rispetto al debutto dell'anno scorso, sembra fare fatica a trovare una propria dimensione e un equilibrio tra vicende principali e secondarie. The dreaM\u00a0non fa eccezione e riesce a portare allo\u2026","rel":"","context":"In &quot;Film e telefilm&quot;","block_context":{"text":"Film e telefilm","link":"https:\/\/oldmanaries.it\/index.php\/category\/film-e-telefilm\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/b2.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/b2.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/b2.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/b2.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/oldmanaries.it\/wp-content\/uploads\/2021\/04\/b2.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":770,"url":"https:\/\/oldmanaries.it\/index.php\/2008\/02\/04\/le-13-perle\/","url_meta":{"origin":1002,"position":2},"title":"Le 13 perle&#8230;","author":"Aries","date":"4 Febbraio 2008","format":false,"excerpt":"Per favore, ve lo chiedo a nome di tutti gli informatici di professione. Se ne incontrate uno EVITATE di dirgli una qualsiasi delle seguenti frasi che, ve lo assicuro, alla centesima volta che si sentono causano gravi attacchi di orchite. Sezione insicuri: - Ah, io\u00a0 quella roba l\u00ec dei computer\u2026","rel":"","context":"In &quot;Still life&quot;","block_context":{"text":"Still life","link":"https:\/\/oldmanaries.it\/index.php\/category\/still-life\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5059,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/01\/20\/282-inutili-riflessioni-di-un-blogger-quarantenne\/","url_meta":{"origin":1002,"position":3},"title":"282. Inutili riflessioni di un blogger quarantenne","author":"Aries","date":"20 Gennaio 2016","format":false,"excerpt":"Che l'avvento dei social abbia cambiato faccia ai blog \u00e8 un dato di fatto.Molti non sono sopravvissuti: chi li teneva \u00e8 migrato verso piattaforme pi\u00f9 immediate e, per quanto mi riguarda, meno soddisfacenti; altri si sono trasformati, qualcuno \u00e8 nato, qualcuno (come questo) ha proseguito la sua strada, ma tutti,\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":5226,"url":"https:\/\/oldmanaries.it\/index.php\/2016\/03\/18\/343-non-e-una-parolaccia\/","url_meta":{"origin":1002,"position":4},"title":"340. Non \u00e8 una parolaccia","author":"Aries","date":"18 Marzo 2016","format":false,"excerpt":"\u00c8 da un po' che gira in rete un video (che trovate in fondo al post) in cui, in pochi minuti, si spiega meravigliosamente cosa sia l'empatia. La parola \"empatia\" \u00e8 spesso abusata, utilizzata a sproposito, un po' come tutte le parole che possono superficialmente sembrare semplici e che solo\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":4315,"url":"https:\/\/oldmanaries.it\/index.php\/2015\/04\/16\/4-ironia-chi-ce-lha-chi-dice-di-averla\/","url_meta":{"origin":1002,"position":5},"title":"4. Ironia. Chi ce l&#8217;ha. Chi dice di averla.","author":"Aries","date":"16 Aprile 2015","format":false,"excerpt":"Di \"legittimazione\" all'ironia e alla battuta ho gi\u00e0 parlato qui sopra, ma vediamo di fare un riassunto prima di parlare della causa scatenante di questo post. Primo assioma. Non tutte le battute sono lecite. Secondo assioma. Le liceit\u00e0 di una battuta non \u00e8 (solo) legata al contenuto della stessa, ma\u2026","rel":"","context":"In &quot;Riflessioni&quot;","block_context":{"text":"Riflessioni","link":"https:\/\/oldmanaries.it\/index.php\/category\/riflessioni\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/comments?post=1002"}],"version-history":[{"count":0,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/posts\/1002\/revisions"}],"wp:attachment":[{"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/media?parent=1002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/categories?post=1002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/oldmanaries.it\/index.php\/wp-json\/wp\/v2\/tags?post=1002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}